{"id":15,"date":"2018-08-06T18:25:43","date_gmt":"2018-08-06T16:25:43","guid":{"rendered":"https:\/\/2018.madrid.wordcamp.org\/?page_id=15"},"modified":"2018-08-06T18:25:43","modified_gmt":"2018-08-06T16:25:43","slug":"videos","status":"publish","type":"page","link":"https:\/\/madrid.wordcamp.org\/2018\/videos\/","title":{"rendered":"Videos"},"content":{"rendered":"\t\t\t\t<ul class=\"wptv-videos\">\n\t\t\t\t\t\t\t\t\t\t\t<li class=\"wptv-video-item\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/wordpress.tv\/2018\/05\/16\/angel-g-zinsel-miedo-y-panico-a-hablar-en-publico\/\">\n\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/videos.files.wordpress.com\/LLPz33bx\/video-9b4c981f79_scruberthumbnail_0.jpg\" alt=\"\u00c1ngel G. Zinsel: Miedo y P\u00c1NICO a hablar en p\u00fablico\" \/>\n\t\t\t\t\t\t\t\t<span class=\"wptv-video-caption\">\u00c1ngel G. Zinsel: Miedo y P\u00c1NICO a hablar en p\u00fablico<\/span>\n\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t<li class=\"wptv-video-item\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/wordpress.tv\/2018\/05\/16\/jepser-bernardino-sitios-web-estaticos-con-wordpress-y-react\/\">\n\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/videos.files.wordpress.com\/E8YTWucF\/video-0db6072143_scruberthumbnail_0.jpg\" alt=\"Jepser Bernardino: Sitios web est\u00e1ticos con WordPress y React\" \/>\n\t\t\t\t\t\t\t\t<span class=\"wptv-video-caption\">Jepser Bernardino: Sitios web est\u00e1ticos con WordPress y React<\/span>\n\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t<li class=\"wptv-video-item\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/wordpress.tv\/2018\/05\/10\/david-navia-matas-wap-rwd-amp-pwa-pero-wtf\/\">\n\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/videos.files.wordpress.com\/q16kyn1e\/video-2003cb142f_dvd.original.jpg\" alt=\"David Navia Matas: WAP, RWD, AMP, PWA\u2026 pero WTF!\" \/>\n\t\t\t\t\t\t\t\t<span class=\"wptv-video-caption\">David Navia Matas: WAP, RWD, AMP, PWA\u2026 pero WTF!<\/span>\n\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t<li class=\"wptv-video-item\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/wordpress.tv\/2018\/05\/10\/juan-hernando-wordpress-no-es-solamente-para-blogs-pero-hazte-uno\/\">\n\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/videos.files.wordpress.com\/2aIIQ028\/video-d03d7ecd91_dvd.original.jpg\" alt=\"Juan Hernando: WordPress no es solamente para blogs, pero hazte uno\" \/>\n\t\t\t\t\t\t\t\t<span class=\"wptv-video-caption\">Juan Hernando: WordPress no es solamente para blogs, pero hazte uno<\/span>\n\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t<li class=\"wptv-video-item\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/wordpress.tv\/2018\/05\/10\/fernando-tellado-como-ser-una-wordpress-star-y-ganar-fans-y-haters\/\">\n\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/videos.files.wordpress.com\/1CVWGuA3\/video-992208a0ab_dvd.original.jpg\" alt=\"Fernando Tellado: C\u00f3mo ser una WordPress Star y ganar fans y haters\" \/>\n\t\t\t\t\t\t\t\t<span class=\"wptv-video-caption\">Fernando Tellado: C\u00f3mo ser una WordPress Star y ganar fans y haters<\/span>\n\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t<li class=\"wptv-video-item\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/wordpress.tv\/2018\/05\/10\/beatriz-lavela-perez-compositores-visuales-guarden-los-cuchillos\/\">\n\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/videos.files.wordpress.com\/pFaS4V8U\/video-4d469a2eea_dvd.original.jpg\" alt=\"Beatriz Lavela P\u00e9rez: Compositores visuales, guarden los cuchillos\" \/>\n\t\t\t\t\t\t\t\t<span class=\"wptv-video-caption\">Beatriz Lavela P\u00e9rez: Compositores visuales, guarden los cuchillos<\/span>\n\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t<li class=\"wptv-video-item\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/wordpress.tv\/2018\/05\/09\/david-aguilera-de-la-pagina-en-blanco-al-exito-que-pasos-debes-seguir\/\">\n\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/videos.files.wordpress.com\/TdRvIprR\/video-b68b420feb_dvd.original.jpg\" alt=\"David Aguilera: De la p\u00e1gina en blanco al \u00e9xito: qu\u00e9 pasos debes seguir\" \/>\n\t\t\t\t\t\t\t\t<span class=\"wptv-video-caption\">David Aguilera: De la p\u00e1gina en blanco al \u00e9xito: qu\u00e9 pasos debes seguir<\/span>\n\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t<li class=\"wptv-video-item\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/wordpress.tv\/2018\/05\/09\/laura-diaz-como-limpiar-un-wordpress-con-sindrome-de-diogenes\/\">\n\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/videos.files.wordpress.com\/uvzWQQ9q\/video-6ab19f01d3_dvd.original.jpg\" alt=\"Laura D\u00edaz: C\u00f3mo limpiar un WordPress con s\u00edndrome de Di\u00f3genes\" \/>\n\t\t\t\t\t\t\t\t<span class=\"wptv-video-caption\">Laura D\u00edaz: C\u00f3mo limpiar un WordPress con s\u00edndrome de Di\u00f3genes<\/span>\n\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t<li class=\"wptv-video-item\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/wordpress.tv\/2018\/05\/09\/marco-russo-git-de-la-guarda-dulce-compania\/\">\n\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/videos.files.wordpress.com\/OoSGymEE\/video-20c1ea236d_dvd.original.jpg\" alt=\"Marco Russo: GIT de la guarda, dulce compa\u00f1\u00eda\" \/>\n\t\t\t\t\t\t\t\t<span class=\"wptv-video-caption\">Marco Russo: GIT de la guarda, dulce compa\u00f1\u00eda<\/span>\n\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t<li class=\"wptv-video-item\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/wordpress.tv\/2018\/05\/09\/jaime-garmar-empieza-con-buen-pie-al-instalar-wordpress\/\">\n\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/videos.files.wordpress.com\/Q9DJNAWV\/video-604988d8f4_dvd.original.jpg\" alt=\"Jaime Garmar: Empieza con buen pie al instalar WordPress\" \/>\n\t\t\t\t\t\t\t\t<span class=\"wptv-video-caption\">Jaime Garmar: Empieza con buen pie al instalar WordPress<\/span>\n\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t<\/ul>\n\t\t\t <!-- served from cache -->\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1320655,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-15","page","type-page","status-publish","hentry"],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/PheMPy-f","_links":{"self":[{"href":"https:\/\/madrid.wordcamp.org\/2018\/wp-json\/wp\/v2\/pages\/15","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/madrid.wordcamp.org\/2018\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/madrid.wordcamp.org\/2018\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/madrid.wordcamp.org\/2018\/wp-json\/wp\/v2\/users\/1320655"}],"replies":[{"embeddable":true,"href":"https:\/\/madrid.wordcamp.org\/2018\/wp-json\/wp\/v2\/comments?post=15"}],"version-history":[{"count":1,"href":"https:\/\/madrid.wordcamp.org\/2018\/wp-json\/wp\/v2\/pages\/15\/revisions"}],"predecessor-version":[{"id":4444,"href":"https:\/\/madrid.wordcamp.org\/2018\/wp-json\/wp\/v2\/pages\/15\/revisions\/4444"}],"wp:attachment":[{"href":"https:\/\/madrid.wordcamp.org\/2018\/wp-json\/wp\/v2\/media?parent=15"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}