{"id":1311,"date":"2018-03-08T09:45:24","date_gmt":"2018-03-08T08:45:24","guid":{"rendered":"https:\/\/2018.madrid.wordcamp.org\/?p=1311"},"modified":"2018-03-08T09:53:52","modified_gmt":"2018-03-08T08:53:52","slug":"vas-a-perderte-el-evento-wordpress-del-ano-entradas-ya-disponibles-para-wordcamp-madrid-2018","status":"publish","type":"post","link":"https:\/\/madrid.wordcamp.org\/2018\/uncategorized\/vas-a-perderte-el-evento-wordpress-del-ano-entradas-ya-disponibles-para-wordcamp-madrid-2018\/","title":{"rendered":"\u00bfVas a perderte el evento\u00a0WordPress del a\u00f1o? Entradas ya disponibles para WordCamp Madrid 2018"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-1318\" src=\"https:\/\/2018.madrid.wordcamp.org\/files\/2018\/03\/captura-2018-03-07-a-las-19.25.26.png\" alt=\"entrada wordcamp madrid 2018\" width=\"614\" height=\"246\" srcset=\"https:\/\/madrid.wordcamp.org\/2018\/files\/2018\/03\/captura-2018-03-07-a-las-19.25.26.png 614w, https:\/\/madrid.wordcamp.org\/2018\/files\/2018\/03\/captura-2018-03-07-a-las-19.25.26-300x120.png 300w, https:\/\/madrid.wordcamp.org\/2018\/files\/2018\/03\/captura-2018-03-07-a-las-19.25.26-500x200.png 500w\" sizes=\"auto, (max-width: 614px) 100vw, 614px\" \/><\/p>\n<p>\u00bfDe verdad vas a perderte el evento\u00a0WordPress del a\u00f1o?<\/p>\n<p>Si tienes\u00a0claro que\u00a0\u00ab<em>ni de co\u00f1a<\/em>\u00bb ya tardas en hacer <a href=\"https:\/\/2018.madrid.wordcamp.org\/entradas\/\"><strong>CLIC AQU\u00cd PARA ADQUIRIR TU ENTRADA ANTES DE QUE SE ACABEN<\/strong><\/a>.<\/p>\n<p>Si a\u00fan no lo tienes claro, bueno, lo comprendemos, aqu\u00ed tienes algunos argumentos para que no te lo pienses mucho:<\/p>\n<h2>\u00bfA qu\u00e9 me da derecho la entrada?<\/h2>\n<p>Por unos rid\u00edculos y simb\u00f3licos 25\u20ac tienes acceso a nada menos que\u2026<\/p>\n<ul>\n<li><a href=\"https:\/\/2018.madrid.wordcamp.org\/programa\/\">Ponencias<\/a> de profesionales nacionales e internacionales de primer nivel, que adem\u00e1s no cobran por su participaci\u00f3n.<\/li>\n<li>Contributor Day, en el que participar del presente y futuro de WordPress.<\/li>\n<li>Fiesta de la comunidad.<\/li>\n<li>Networking con los mayores profesionales y empresas relacionadas con WordPress y todo su ecosistema.<\/li>\n<li>Desayuno, comida, caf\u00e9 y aperitivos durante las dos jornadas (ponencias y\u00a0<em>contributor day<\/em>).<\/li>\n<li>Regalos de WordCamp Madrid (camiseta, recuerdos, pegatinas, descuentos especiales de los patrocinadores)<\/li>\n<li>Regalos de <a href=\"https:\/\/2018.madrid.wordcamp.org\/patrocinadores\/\">los patrocinadores<\/a>, que siempre hacen regalos y descuentos exclusivos en los eventos WordPress.<\/li>\n<li>Participar en el evento del que todo el mundo va a hablar.<\/li>\n<\/ul>\n<p>\u00bfM\u00e1s detalle?\u2026<\/p>\n<h2>Las ponencias<\/h2>\n<p>Asistiendo a WordCamp Madrid podr\u00e1s aprender todo lo relacioinado con WordPress de la mano de los mayores profesionales de marketing, SEO, contenidos, desarrollo, dise\u00f1o, negocio, etc.<\/p>\n<p>Tenemos a los mejores ponentes nacionales e internacionales que, <a href=\"https:\/\/2018.madrid.wordcamp.org\/programa\/\" target=\"_blank\" rel=\"noopener\">en 29 ponencias simult\u00e1neas<\/a>, te ense\u00f1ar\u00e1n todos sus secretos y experiencia para potenciar tu presencia online gracias a WordPress, el sistema de creaci\u00f3n web que impulsa el 30% de Internet.<\/p>\n<h2>Contributor Day<\/h2>\n<p>Por si esto fuese poco, el domingo 22 de abril tiene lugar <a href=\"https:\/\/2018.madrid.wordcamp.org\/#contributor\" target=\"_blank\" rel=\"noopener\">el Contributor Day<\/a>, en el que podr\u00e1s formar parte de la \u00e9lite de usuarios de WordPress que hacen que sea posible.<\/p>\n<p>De la mano de algunos de los profesionales WordPress m\u00e1s reputados aprender\u00e1s a participar en el proyecto WordPress, para que este CMS tambi\u00e9n tenga un poquito de ti.<\/p>\n<p>No hace falta ser programador, cualquiera puede ayudar a hacer WordPress. Puedes ayudar en las traducciones de tus plugins y temas favoritos, revisar temas y plugins, ayudar a otros usuarios en los foros, y mucho m\u00e1s, y s\u00ed, tambi\u00e9n a crear el pr\u00f3ximo c\u00f3digo de WordPress.<\/p>\n<h2>Networking<\/h2>\n<p>Durante los dos d\u00edas del evento vas a tener a mano a los mayores profesionales WordPress y a las mejores empresas y emprendedores de Internet.<\/p>\n<p>Podr\u00e1s encontrar tu pr\u00f3ximo programador, crear un equipo para tu pr\u00f3ximo proyecto, desarrollar negocio, aprender, compartir, crecer, emprender.<\/p>\n<p>Si hablas con alguien que alguna vez haya asistido a un evento WordCamp\u00a0 seguramente coincidir\u00e1 en que, adem\u00e1s de las ponencias, el poder hablar y compartir con los grandes profesionales que all\u00ed se encuentran, es gratis, y de un valor incalculable, igual que WordPress.<\/p>\n<p>Ya sea entre ponencias, durante la comida, en la fiesta de la comunidad o en el Contributor Day (especialmente) vas a tener oportunidades de todo tipo, para tu presente y futuro profesional.<\/p>\n<h2>Patrocinadores<\/h2>\n<p>En WordCamp Madrid 2018 encontrar\u00e1s stands de <a href=\"https:\/\/2018.madrid.wordcamp.org\/patrocinadores\/\">las empresas m\u00e1s relevantes<\/a> que ofrecen productos y servicios WordPress.<\/p>\n<p>No solo tendr\u00e1s acceso a los CEOs, jefes de producto y responsables t\u00e9cnicos de las mejores empresas sino que tambi\u00e9n suelen ofrecer regalos y descuentos exclusivos.<\/p>\n<h2>\u00bfConvencido?<\/h2>\n<p>Si te parecen suficientes argumentos no tardes, que se acaban enseguida y luego todo son lamentos\u2026<\/p>\n<p style=\"text-align: left\"><a href=\"https:\/\/2018.madrid.wordcamp.org\/entradas\/\"><strong>CLIC AQU\u00cd PARA ADQUIRIR TU ENTRADA DE WORDCAMP MADRID 2018<\/strong><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00bfDe verdad vas a perderte el evento\u00a0WordPress del a\u00f1o? Si tienes\u00a0claro que\u00a0\u00abni de co\u00f1a\u00bb ya tardas en hacer CLIC AQU\u00cd PARA ADQUIRIR TU ENTRADA ANTES DE QUE SE ACABEN. Si a\u00fan no lo tienes claro, bueno, lo comprendemos, aqu\u00ed tienes &hellip; <a href=\"https:\/\/madrid.wordcamp.org\/2018\/uncategorized\/vas-a-perderte-el-evento-wordpress-del-ano-entradas-ya-disponibles-para-wordcamp-madrid-2018\/\">Seguir leyendo <span class=\"assistive-text\">\u00bfVas a perderte el evento\u00a0WordPress del a\u00f1o? Entradas ya disponibles para WordCamp Madrid 2018<\/span> <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":1320655,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[1],"tags":[],"class_list":["post-1311","post","type-post","status-publish","format-standard","hentry","category-uncategorized"],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pheMPy-l9","jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/madrid.wordcamp.org\/2018\/wp-json\/wp\/v2\/posts\/1311","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/madrid.wordcamp.org\/2018\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/madrid.wordcamp.org\/2018\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/madrid.wordcamp.org\/2018\/wp-json\/wp\/v2\/users\/1320655"}],"replies":[{"embeddable":true,"href":"https:\/\/madrid.wordcamp.org\/2018\/wp-json\/wp\/v2\/comments?post=1311"}],"version-history":[{"count":7,"href":"https:\/\/madrid.wordcamp.org\/2018\/wp-json\/wp\/v2\/posts\/1311\/revisions"}],"predecessor-version":[{"id":1320,"href":"https:\/\/madrid.wordcamp.org\/2018\/wp-json\/wp\/v2\/posts\/1311\/revisions\/1320"}],"wp:attachment":[{"href":"https:\/\/madrid.wordcamp.org\/2018\/wp-json\/wp\/v2\/media?parent=1311"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/madrid.wordcamp.org\/2018\/wp-json\/wp\/v2\/categories?post=1311"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/madrid.wordcamp.org\/2018\/wp-json\/wp\/v2\/tags?post=1311"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}