{"id":449,"date":"2018-03-05T20:20:18","date_gmt":"2018-03-05T19:20:18","guid":{"rendered":"https:\/\/2018.madrid.wordcamp.org\/?post_type=wcb_speaker&#038;p=449"},"modified":"2018-04-13T13:00:48","modified_gmt":"2018-04-13T11:00:48","slug":"ana-cirujano","status":"publish","type":"wcb_speaker","link":"https:\/\/madrid.wordcamp.org\/2018\/speaker\/ana-cirujano\/","title":{"rendered":"Ana Cirujano"},"content":{"rendered":"<p>Me licenci\u00e9 en Sociolog\u00eda en 2005 y nunca he dejado de formarme: Dise\u00f1o multimedia, Direcci\u00f3n Comercial y Marketing, Impro, Desarrollo web con WordPress&#8230;<\/p>\n<p>He trabajado durante diez a\u00f1os como dise\u00f1adora editorial y, desde 2016, soy aut\u00f3noma y me dedico a hacer p\u00e1ginas web para pymes con WordPress.<\/p>\n<p>Colaboro activamente en la Comunidad WordPress desde 2017, compartiendo conocimiento, traduciendo plugins y participando en los foros de soporte.<\/p>\n<p>Web: <a href=\"https:\/\/www.anacirujano.com\/\">Ana Cirujano<\/a><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-large wp-image-2297\" src=\"https:\/\/2018.madrid.wordcamp.org\/files\/2018\/03\/4-ana-cirujano-1024x590.png\" alt=\"\" width=\"640\" height=\"369\" srcset=\"https:\/\/madrid.wordcamp.org\/2018\/files\/2018\/03\/4-ana-cirujano-1024x590.png 1024w, https:\/\/madrid.wordcamp.org\/2018\/files\/2018\/03\/4-ana-cirujano-300x173.png 300w, https:\/\/madrid.wordcamp.org\/2018\/files\/2018\/03\/4-ana-cirujano-768x443.png 768w, https:\/\/madrid.wordcamp.org\/2018\/files\/2018\/03\/4-ana-cirujano-500x288.png 500w, https:\/\/madrid.wordcamp.org\/2018\/files\/2018\/03\/4-ana-cirujano-1000x576.png 1000w, https:\/\/madrid.wordcamp.org\/2018\/files\/2018\/03\/4-ana-cirujano.png 1923w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Me licenci\u00e9 en Sociolog\u00eda en 2005 y nunca he dejado de formarme: Dise\u00f1o multimedia, Direcci\u00f3n Comercial y Marketing, Impro, Desarrollo web con WordPress&#8230; He trabajado durante diez a\u00f1os como dise\u00f1adora editorial y, desde 2016, soy aut\u00f3noma y me dedico a &hellip; <a href=\"https:\/\/madrid.wordcamp.org\/2018\/speaker\/ana-cirujano\/\">Seguir leyendo <span class=\"assistive-text\">Ana Cirujano<\/span> <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":7694169,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"_wcpt_user_name":"acirujano","footnotes":""},"speaker_group":[],"class_list":["post-449","wcb_speaker","type-wcb_speaker","status-publish","hentry"],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pheMPy-7f","avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/83b21ee2f405251b0d09d91c3b56764b8ef19fd81cae4954dacd1520a7ab26cc?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/83b21ee2f405251b0d09d91c3b56764b8ef19fd81cae4954dacd1520a7ab26cc?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/83b21ee2f405251b0d09d91c3b56764b8ef19fd81cae4954dacd1520a7ab26cc?s=96&d=mm&r=g","128":"https:\/\/secure.gravatar.com\/avatar\/83b21ee2f405251b0d09d91c3b56764b8ef19fd81cae4954dacd1520a7ab26cc?s=128&d=mm&r=g","256":"https:\/\/secure.gravatar.com\/avatar\/83b21ee2f405251b0d09d91c3b56764b8ef19fd81cae4954dacd1520a7ab26cc?s=256&d=mm&r=g","512":"https:\/\/secure.gravatar.com\/avatar\/83b21ee2f405251b0d09d91c3b56764b8ef19fd81cae4954dacd1520a7ab26cc?s=512&d=mm&r=g"},"_links":{"self":[{"href":"https:\/\/madrid.wordcamp.org\/2018\/wp-json\/wp\/v2\/speakers\/449","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/madrid.wordcamp.org\/2018\/wp-json\/wp\/v2\/speakers"}],"about":[{"href":"https:\/\/madrid.wordcamp.org\/2018\/wp-json\/wp\/v2\/types\/wcb_speaker"}],"author":[{"embeddable":true,"href":"https:\/\/madrid.wordcamp.org\/2018\/wp-json\/wp\/v2\/users\/7694169"}],"replies":[{"embeddable":true,"href":"https:\/\/madrid.wordcamp.org\/2018\/wp-json\/wp\/v2\/comments?post=449"}],"version-history":[{"count":4,"href":"https:\/\/madrid.wordcamp.org\/2018\/wp-json\/wp\/v2\/speakers\/449\/revisions"}],"predecessor-version":[{"id":2298,"href":"https:\/\/madrid.wordcamp.org\/2018\/wp-json\/wp\/v2\/speakers\/449\/revisions\/2298"}],"sessions":[{"embeddable":true,"href":"https:\/\/madrid.wordcamp.org\/2018\/wp-json\/wp\/v2\/sessions\/737?_embed=1&context=view"}],"wp:attachment":[{"href":"https:\/\/madrid.wordcamp.org\/2018\/wp-json\/wp\/v2\/media?parent=449"}],"wp:term":[{"taxonomy":"wcb_speaker_group","embeddable":true,"href":"https:\/\/madrid.wordcamp.org\/2018\/wp-json\/wp\/v2\/speaker_group?post=449"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}