{"id":512,"date":"2018-03-05T20:48:28","date_gmt":"2018-03-05T19:48:28","guid":{"rendered":"https:\/\/2018.madrid.wordcamp.org\/?post_type=wcb_speaker&#038;p=512"},"modified":"2018-04-15T19:24:12","modified_gmt":"2018-04-15T17:24:12","slug":"ibon-azkoitia","status":"publish","type":"wcb_speaker","link":"https:\/\/madrid.wordcamp.org\/2018\/speaker\/ibon-azkoitia\/","title":{"rendered":"Ibon Azkoitia"},"content":{"rendered":"<p>Muy buenas, soy Ibon Azkoitia y no tengo una biograf\u00eda como tal\u2026 soy de Bilbao pero actualmente vivo en Madrid y trabajo en <a href=\"https:\/\/www.siteground.es\" rel=\"nofollow\">SiteGround<\/a> como coordinador de eventos.<\/p>\n<p>Colabora de forma activa en la comunidad de WordPress, Organizador de la Comunidad <a href=\"https:\/\/www.wpbilbao.es\/\">WordPress Bilbao<\/a>, ayuda a nuevos organizadores de Meetups y colabora en la p\u00e1gina de la Comunidad WordPress Espa\u00f1a y en las traducciones de WordPress.<\/p>\n<p>Digamos que mi vida est\u00e1 muy orientada a WordPress y su comunidad.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-large wp-image-2410\" src=\"https:\/\/2018.madrid.wordcamp.org\/files\/2018\/03\/8-ibon-azkoitia-1024x576.jpg\" alt=\"\" width=\"640\" height=\"360\" srcset=\"https:\/\/madrid.wordcamp.org\/2018\/files\/2018\/03\/8-ibon-azkoitia-1024x576.jpg 1024w, https:\/\/madrid.wordcamp.org\/2018\/files\/2018\/03\/8-ibon-azkoitia-300x169.jpg 300w, https:\/\/madrid.wordcamp.org\/2018\/files\/2018\/03\/8-ibon-azkoitia-768x432.jpg 768w, https:\/\/madrid.wordcamp.org\/2018\/files\/2018\/03\/8-ibon-azkoitia-500x281.jpg 500w, https:\/\/madrid.wordcamp.org\/2018\/files\/2018\/03\/8-ibon-azkoitia-1000x563.jpg 1000w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Muy buenas, soy Ibon Azkoitia y no tengo una biograf\u00eda como tal\u2026 soy de Bilbao pero actualmente vivo en Madrid y trabajo en SiteGround como coordinador de eventos. Colabora de forma activa en la comunidad de WordPress, Organizador de la &hellip; <a href=\"https:\/\/madrid.wordcamp.org\/2018\/speaker\/ibon-azkoitia\/\">Seguir leyendo <span class=\"assistive-text\">Ibon Azkoitia<\/span> <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":7694169,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"_wcpt_user_name":"IbonAzkoitia","footnotes":""},"speaker_group":[],"class_list":["post-512","wcb_speaker","type-wcb_speaker","status-publish","hentry"],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pheMPy-8g","avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/7462a56a5788a705cfe73dcccd1f3c61a3dde728083f6dd4a4b0bbf26f7974e3?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/7462a56a5788a705cfe73dcccd1f3c61a3dde728083f6dd4a4b0bbf26f7974e3?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/7462a56a5788a705cfe73dcccd1f3c61a3dde728083f6dd4a4b0bbf26f7974e3?s=96&d=mm&r=g","128":"https:\/\/secure.gravatar.com\/avatar\/7462a56a5788a705cfe73dcccd1f3c61a3dde728083f6dd4a4b0bbf26f7974e3?s=128&d=mm&r=g","256":"https:\/\/secure.gravatar.com\/avatar\/7462a56a5788a705cfe73dcccd1f3c61a3dde728083f6dd4a4b0bbf26f7974e3?s=256&d=mm&r=g","512":"https:\/\/secure.gravatar.com\/avatar\/7462a56a5788a705cfe73dcccd1f3c61a3dde728083f6dd4a4b0bbf26f7974e3?s=512&d=mm&r=g"},"_links":{"self":[{"href":"https:\/\/madrid.wordcamp.org\/2018\/wp-json\/wp\/v2\/speakers\/512","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/madrid.wordcamp.org\/2018\/wp-json\/wp\/v2\/speakers"}],"about":[{"href":"https:\/\/madrid.wordcamp.org\/2018\/wp-json\/wp\/v2\/types\/wcb_speaker"}],"author":[{"embeddable":true,"href":"https:\/\/madrid.wordcamp.org\/2018\/wp-json\/wp\/v2\/users\/7694169"}],"replies":[{"embeddable":true,"href":"https:\/\/madrid.wordcamp.org\/2018\/wp-json\/wp\/v2\/comments?post=512"}],"version-history":[{"count":5,"href":"https:\/\/madrid.wordcamp.org\/2018\/wp-json\/wp\/v2\/speakers\/512\/revisions"}],"predecessor-version":[{"id":2411,"href":"https:\/\/madrid.wordcamp.org\/2018\/wp-json\/wp\/v2\/speakers\/512\/revisions\/2411"}],"sessions":[{"embeddable":true,"href":"https:\/\/madrid.wordcamp.org\/2018\/wp-json\/wp\/v2\/sessions\/517?_embed=1&context=view"}],"wp:attachment":[{"href":"https:\/\/madrid.wordcamp.org\/2018\/wp-json\/wp\/v2\/media?parent=512"}],"wp:term":[{"taxonomy":"wcb_speaker_group","embeddable":true,"href":"https:\/\/madrid.wordcamp.org\/2018\/wp-json\/wp\/v2\/speaker_group?post=512"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}