{"id":647,"date":"2018-03-05T20:42:59","date_gmt":"2018-03-05T19:42:59","guid":{"rendered":"https:\/\/2018.madrid.wordcamp.org\/?post_type=wcb_speaker&#038;p=647"},"modified":"2018-04-13T13:04:10","modified_gmt":"2018-04-13T11:04:10","slug":"rocio-valdivia","status":"publish","type":"wcb_speaker","link":"https:\/\/madrid.wordcamp.org\/2018\/speaker\/rocio-valdivia\/","title":{"rendered":"Roc\u00edo Valdivia"},"content":{"rendered":"<p>Enamorada del software libre, la tecnolog\u00eda, los viajes y los retos personales.<\/p>\n<p>Trabajo en <a href=\"https:\/\/automattic.com\/\">Automattic<\/a> como <em>Community Wrangler<\/em> para <a href=\"https:\/\/central.wordcamp.org\/\">WordCamp Central<\/a>.<\/p>\n<p>Con m\u00e1s de 8 a\u00f1os de experiencia con WordPress donde me especializ\u00e9 en la herramienta Buddypress para el desarrollo de redes sociales. Tuve el honor de ser la primera y \u00fanica ponente espa\u00f1ola en las dos primeras ediciones de WordCamp Europa en Leiden (2013) y Sofia (2014).<\/p>\n<p>Miembro del equipo de organizaci\u00f3n de tres WordCamps Sevilla y de WordCamp Europa 2015, 2016 y 2017. Co-autora del libro \u201c<a href=\"https:\/\/www.amazon.es\/WordPress-para-Dummies-Luis-Rull-ebook\/dp\/B00A8SRXHW\/ref=sr_1_1?s=digital-text&amp;ie=UTF8&amp;qid=1520430267&amp;sr=1-1\">WordPress para Dummies<\/a>\u201d (2012), moderadora de los foros en espa\u00f1ol de WordPress, validadora de las traducciones de WordPress y BuddyPress.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-large wp-image-2304\" src=\"https:\/\/2018.madrid.wordcamp.org\/files\/2018\/03\/7-rocio-valdivia-1024x590.png\" alt=\"\" width=\"640\" height=\"369\" srcset=\"https:\/\/madrid.wordcamp.org\/2018\/files\/2018\/03\/7-rocio-valdivia-1024x590.png 1024w, https:\/\/madrid.wordcamp.org\/2018\/files\/2018\/03\/7-rocio-valdivia-300x173.png 300w, https:\/\/madrid.wordcamp.org\/2018\/files\/2018\/03\/7-rocio-valdivia-768x443.png 768w, https:\/\/madrid.wordcamp.org\/2018\/files\/2018\/03\/7-rocio-valdivia-500x288.png 500w, https:\/\/madrid.wordcamp.org\/2018\/files\/2018\/03\/7-rocio-valdivia-1000x576.png 1000w, https:\/\/madrid.wordcamp.org\/2018\/files\/2018\/03\/7-rocio-valdivia.png 1923w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Enamorada del software libre, la tecnolog\u00eda, los viajes y los retos personales. Trabajo en Automattic como Community Wrangler para WordCamp Central. Con m\u00e1s de 8 a\u00f1os de experiencia con WordPress donde me especializ\u00e9 en la herramienta Buddypress para el desarrollo &hellip; <a href=\"https:\/\/madrid.wordcamp.org\/2018\/speaker\/rocio-valdivia\/\">Seguir leyendo <span class=\"assistive-text\">Roc\u00edo Valdivia<\/span> <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":7694169,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"_wcpt_user_name":"_DorsVenabili","footnotes":""},"speaker_group":[],"class_list":["post-647","wcb_speaker","type-wcb_speaker","status-publish","hentry"],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pheMPy-ar","avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/17e3cbd63c4ddcf873d1848277de062a48239d962359ecaf1978e966429f5b6f?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/17e3cbd63c4ddcf873d1848277de062a48239d962359ecaf1978e966429f5b6f?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/17e3cbd63c4ddcf873d1848277de062a48239d962359ecaf1978e966429f5b6f?s=96&d=mm&r=g","128":"https:\/\/secure.gravatar.com\/avatar\/17e3cbd63c4ddcf873d1848277de062a48239d962359ecaf1978e966429f5b6f?s=128&d=mm&r=g","256":"https:\/\/secure.gravatar.com\/avatar\/17e3cbd63c4ddcf873d1848277de062a48239d962359ecaf1978e966429f5b6f?s=256&d=mm&r=g","512":"https:\/\/secure.gravatar.com\/avatar\/17e3cbd63c4ddcf873d1848277de062a48239d962359ecaf1978e966429f5b6f?s=512&d=mm&r=g"},"_links":{"self":[{"href":"https:\/\/madrid.wordcamp.org\/2018\/wp-json\/wp\/v2\/speakers\/647","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/madrid.wordcamp.org\/2018\/wp-json\/wp\/v2\/speakers"}],"about":[{"href":"https:\/\/madrid.wordcamp.org\/2018\/wp-json\/wp\/v2\/types\/wcb_speaker"}],"author":[{"embeddable":true,"href":"https:\/\/madrid.wordcamp.org\/2018\/wp-json\/wp\/v2\/users\/7694169"}],"replies":[{"embeddable":true,"href":"https:\/\/madrid.wordcamp.org\/2018\/wp-json\/wp\/v2\/comments?post=647"}],"version-history":[{"count":4,"href":"https:\/\/madrid.wordcamp.org\/2018\/wp-json\/wp\/v2\/speakers\/647\/revisions"}],"predecessor-version":[{"id":2305,"href":"https:\/\/madrid.wordcamp.org\/2018\/wp-json\/wp\/v2\/speakers\/647\/revisions\/2305"}],"sessions":[{"embeddable":true,"href":"https:\/\/madrid.wordcamp.org\/2018\/wp-json\/wp\/v2\/sessions\/1129?_embed=1&context=view"},{"embeddable":true,"href":"https:\/\/madrid.wordcamp.org\/2018\/wp-json\/wp\/v2\/sessions\/648?_embed=1&context=view"}],"wp:attachment":[{"href":"https:\/\/madrid.wordcamp.org\/2018\/wp-json\/wp\/v2\/media?parent=647"}],"wp:term":[{"taxonomy":"wcb_speaker_group","embeddable":true,"href":"https:\/\/madrid.wordcamp.org\/2018\/wp-json\/wp\/v2\/speaker_group?post=647"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}