{"id":2831,"date":"2019-03-09T08:54:03","date_gmt":"2019-03-09T07:54:03","guid":{"rendered":"https:\/\/2019.madrid.wordcamp.org\/?p=2831"},"modified":"2019-03-09T09:00:07","modified_gmt":"2019-03-09T08:00:07","slug":"empieza-por-una-meetup","status":"publish","type":"post","link":"https:\/\/madrid.wordcamp.org\/2019\/empieza-por-una-meetup\/","title":{"rendered":"Camino a WCMAD 2019 \u2013 Episodio 6: Empieza por una Meetup, pero empieza con Fernan D\u00edez, Ciudadano B y Carlos M. Diaz"},"content":{"rendered":"\n<figure class=\"wp-block-audio\"><audio controls src=\"https:\/\/www.ivoox.com\/episodio-6-empieza-meetup-pero-empieza_md_33214484_wp_1.mp3\"><\/audio><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"> Tambi\u00e9n puedes seguir este podcast en&nbsp;<a rel=\"noreferrer noopener\" href=\"https:\/\/itunes.apple.com\/es\/podcast\/camino-a-wordcamp-madrid-2019\/id1451399555?mt=2\" target=\"_blank\">Itunes<\/a>&nbsp;y&nbsp;<a rel=\"noreferrer noopener\" href=\"https:\/\/www.ivoox.com\/podcast-camino-a-wordcamp-madrid-2019_sq_f1659170_1.html\" target=\"_blank\">Ivoox<\/a>. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ya queda nada para que nos veamos en La N@ve y disfrutemos de una fant\u00e1stica <strong>WordCamp Madrid 2019<\/strong>, rodeados de muchos profesionales del sector y un estupendo <a href=\"https:\/\/2019.madrid.wordcamp.org\/schedule\/\" rel=\"nofollow\">programa de ponencias<\/a>.  <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">No te pierdas la entrevista que hemos grabado para hablar sobre por qu\u00e9 tienes que asistir a una Meetup local. Escucha las experiencias de nuestros invitados <a rel=\"noreferrer noopener\" href=\"https:\/\/twitter.com\/Fernan\" target=\"_blank\">Fernan D\u00edez<\/a>, <a rel=\"noreferrer noopener\" href=\"https:\/\/twitter.com\/ciudadanoB\" target=\"_blank\">Juan Hernando<\/a> y <a rel=\"noreferrer noopener\" href=\"https:\/\/twitter.com\/carlosmdh\" target=\"_blank\">Carlos M. D\u00edaz<\/a> de todo lo que tiene que ver con las Meetups sobre WordPress en Espa\u00f1a.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">\u00bfQue es una meetup de WordPress?<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Muchos tenemos nuestra propia definici\u00f3n pero no deja de ser una reuni\u00f3n donde varias personas se re\u00fanen para hablar sobre un tema en concreto, en este caso, sobre WordPress. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Escucha el episodio de hoy para saber m\u00e1s sobre qu\u00e9 es y c\u00f3mo aprovechar una Meetup.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">\u00bfPor qu\u00e9 recomendamos acudir a una meetup?<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Existen varios motivos por los que asistir a meetups es importante si eres emprendedor o tienes inter\u00e9s en un tema en concreto. Acudir a una meetup de WordPress te ayudar\u00e1 a aprender sobre este CMS a coste 0 y a conocer a otras personas de la comunidad. Es un buen inicio para saber que te puedes encontrar en una WordCamp a un nivel m\u00e1s reducido, algo m\u00e1s local.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Si eres emprendedor y\/o usas WordPress, el epis\u00f3dio de hoy es para ti. \u00a1Disfrutalo!<\/p>\n\n\n\n<div class=\"wp-block-button aligncenter is-style-outline is-style-outline--1\"><a class=\"wp-block-button__link has-text-color has-vivid-red-color\" href=\"https:\/\/2019.madrid.wordcamp.org\/tickets\/\" rel=\"nofollow\">Compra ya tu entrada para WCMAD<\/a><\/div>\n","protected":false},"excerpt":{"rendered":"<p>No te pierdas la entrevista que hemos grabado para hablar sobre por qu\u00e9 tienes que asistir a una Meetup local. Escucha las experiencias de nuestros invitados Fernan D\u00edez, Juan Hernando y Carlos M. D\u00edaz de todo lo que tiene que ver con las Meetups sobre WordPress en Espa\u00f1a.<\/p>\n","protected":false},"author":14691952,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[271023],"tags":[],"class_list":["post-2831","post","type-post","status-publish","format-standard","hentry","category-podcast"],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pheMLx-JF","jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/madrid.wordcamp.org\/2019\/wp-json\/wp\/v2\/posts\/2831","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/madrid.wordcamp.org\/2019\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/madrid.wordcamp.org\/2019\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/madrid.wordcamp.org\/2019\/wp-json\/wp\/v2\/users\/14691952"}],"replies":[{"embeddable":true,"href":"https:\/\/madrid.wordcamp.org\/2019\/wp-json\/wp\/v2\/comments?post=2831"}],"version-history":[{"count":5,"href":"https:\/\/madrid.wordcamp.org\/2019\/wp-json\/wp\/v2\/posts\/2831\/revisions"}],"predecessor-version":[{"id":2840,"href":"https:\/\/madrid.wordcamp.org\/2019\/wp-json\/wp\/v2\/posts\/2831\/revisions\/2840"}],"wp:attachment":[{"href":"https:\/\/madrid.wordcamp.org\/2019\/wp-json\/wp\/v2\/media?parent=2831"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/madrid.wordcamp.org\/2019\/wp-json\/wp\/v2\/categories?post=2831"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/madrid.wordcamp.org\/2019\/wp-json\/wp\/v2\/tags?post=2831"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}