{"id":2108,"date":"2019-02-19T01:17:21","date_gmt":"2019-02-19T00:17:21","guid":{"rendered":"https:\/\/2019.madrid.wordcamp.org\/?post_type=wcb_session&#038;p=2108"},"modified":"2019-04-02T11:09:47","modified_gmt":"2019-04-02T09:09:47","slug":"como-desarrollar-en-la-nube-y-trabajar-con-wordpress","status":"publish","type":"wcb_session","link":"https:\/\/madrid.wordcamp.org\/2019\/session\/como-desarrollar-en-la-nube-y-trabajar-con-wordpress\/","title":{"rendered":"Como desarrollar en la nube y trabajar con WordPress"},"content":{"rendered":"\n<figure class=\"wp-block-image\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"360\" data-attachment-id=\"3387\" data-permalink=\"https:\/\/madrid.wordcamp.org\/2019\/speaker\/javier-mendoza\/02-track-a-javier-mendoza\/\" data-orig-file=\"https:\/\/i0.wp.com\/madrid.wordcamp.org\/2019\/files\/2019\/02\/02-track-a-javier-mendoza.jpg?fit=1920%2C1080&amp;ssl=1\" data-orig-size=\"1920,1080\" data-comments-opened=\"0\" data-image-title=\"02-track-a-javier-mendoza\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/madrid.wordcamp.org\/2019\/files\/2019\/02\/02-track-a-javier-mendoza.jpg?fit=640%2C360&amp;ssl=1\" src=\"https:\/\/i0.wp.com\/2019.madrid.wordcamp.org\/files\/2019\/02\/02-track-a-javier-mendoza.jpg?resize=640%2C360&#038;ssl=1\" alt=\"\" class=\"wp-image-3387\" srcset=\"https:\/\/i0.wp.com\/madrid.wordcamp.org\/2019\/files\/2019\/02\/02-track-a-javier-mendoza.jpg?w=1920&amp;ssl=1 1920w, https:\/\/i0.wp.com\/madrid.wordcamp.org\/2019\/files\/2019\/02\/02-track-a-javier-mendoza.jpg?resize=300%2C169&amp;ssl=1 300w, https:\/\/i0.wp.com\/madrid.wordcamp.org\/2019\/files\/2019\/02\/02-track-a-javier-mendoza.jpg?resize=768%2C432&amp;ssl=1 768w, https:\/\/i0.wp.com\/madrid.wordcamp.org\/2019\/files\/2019\/02\/02-track-a-javier-mendoza.jpg?resize=1024%2C576&amp;ssl=1 1024w, https:\/\/i0.wp.com\/madrid.wordcamp.org\/2019\/files\/2019\/02\/02-track-a-javier-mendoza.jpg?resize=500%2C281&amp;ssl=1 500w, https:\/\/i0.wp.com\/madrid.wordcamp.org\/2019\/files\/2019\/02\/02-track-a-javier-mendoza.jpg?w=1280&amp;ssl=1 1280w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>T\u00edtulo de la ponencia:<\/strong>&nbsp;\u00abComo trabajar en la nube y desarrollar con WordPress\u00bb<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Descripci\u00f3n de la ponencia<\/strong>:&nbsp;Esta charla ser\u00e1, muy probablemente, distinta a lo que estas acostumbrado. Lo que quiero ense\u00f1arte es mi forma de trabajar 100% en la nube en la que te mostrare un caso pr\u00e1ctico de desarrollo de un sitio web de principio a fin. En en el que juntos&nbsp; compraremos el dominio, daremos de alta una instancia de servidor en nube, configuraremos nuestro editor (tambi\u00e9n en la nube) mediante SSH y crearemos un sitio web desde cero plenamente operativo y con SSL. Todo en 25 minutos&nbsp; \u00bfDificil? Si \u00bfImposible? Con WordPress y la nube claro que no (o eso espero, jeje xD).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Qu\u00e9 van a aprender los asistentes:<\/strong>&nbsp;Registrar un dominio con Google Domains. Desplegar una instancia de servidor con Digital Ocean a trav\u00e9s de CodeAnyWhere.com. Conectar Digital Ocean y CodeAnywhere para poder trabajar conjuntamente con ambas herramientas. Desplegar un sitio web en WordPress y crear un sitio web b\u00e1sico. Y alg\u00fan truquito m\u00e1s &#8230; <\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Nivel del asistente:<\/strong>&nbsp;Avanzado<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>P\u00fablico objetivo:<\/strong>&nbsp;General, Dise\u00f1o, Desarrollo, Negocio<\/p>\n","protected":false},"excerpt":{"rendered":"<p>T\u00edtulo de la ponencia:&nbsp;\u00abComo trabajar en la nube y desarrollar con WordPress\u00bb Descripci\u00f3n de la ponencia:&nbsp;Esta charla ser\u00e1, muy probablemente, distinta a lo que estas acostumbrado. Lo que quiero ense\u00f1arte es mi forma de trabajar 100% en la nube en la que te mostrare un caso pr\u00e1ctico de desarrollo de un sitio web de principio [&hellip;]<\/p>\n","protected":false},"author":14791143,"featured_media":0,"template":"","meta":{"_wcpt_session_time":1554535800,"_wcpt_session_duration":3000,"_wcpt_session_type":"session","_wcpt_session_slides":"","_wcpt_session_video":"","_wcpt_speaker_id":[1945],"footnotes":""},"session_track":[164407],"session_category":[1260310],"class_list":["post-2108","wcb_session","type-wcb_session","status-publish","hentry","wcb_track-auditorio","wcb_session_category-desarrollo-sysadmin"],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pheMLx-y0","session_date_time":{"date":"6 abril, 2019","time":"09:30"},"session_speakers":[{"id":"1945","slug":"javier-mendoza","name":"Javier Mendoza","link":"https:\/\/madrid.wordcamp.org\/2019\/speaker\/javier-mendoza\/"}],"session_cats_rendered":"Desarrollo","_links":{"self":[{"href":"https:\/\/madrid.wordcamp.org\/2019\/wp-json\/wp\/v2\/sessions\/2108","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/madrid.wordcamp.org\/2019\/wp-json\/wp\/v2\/sessions"}],"about":[{"href":"https:\/\/madrid.wordcamp.org\/2019\/wp-json\/wp\/v2\/types\/wcb_session"}],"version-history":[{"count":6,"href":"https:\/\/madrid.wordcamp.org\/2019\/wp-json\/wp\/v2\/sessions\/2108\/revisions"}],"predecessor-version":[{"id":3507,"href":"https:\/\/madrid.wordcamp.org\/2019\/wp-json\/wp\/v2\/sessions\/2108\/revisions\/3507"}],"speakers":[{"embeddable":true,"href":"https:\/\/madrid.wordcamp.org\/2019\/wp-json\/wp\/v2\/speakers\/1945"}],"author":[{"embeddable":true,"href":"https:\/\/madrid.wordcamp.org\/2019\/wp-json\/wporg\/v1\/users\/cyxmedia"}],"wp:attachment":[{"href":"https:\/\/madrid.wordcamp.org\/2019\/wp-json\/wp\/v2\/media?parent=2108"}],"wp:term":[{"taxonomy":"wcb_track","embeddable":true,"href":"https:\/\/madrid.wordcamp.org\/2019\/wp-json\/wp\/v2\/session_track?post=2108"},{"taxonomy":"wcb_session_category","embeddable":true,"href":"https:\/\/madrid.wordcamp.org\/2019\/wp-json\/wp\/v2\/session_category?post=2108"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}