{"id":2174,"date":"2019-02-19T02:00:55","date_gmt":"2019-02-19T01:00:55","guid":{"rendered":"https:\/\/2019.madrid.wordcamp.org\/?post_type=wcb_session&#038;p=2174"},"modified":"2019-04-02T11:16:41","modified_gmt":"2019-04-02T09:16:41","slug":"git-no-es-cosa-menor-dicho-de-otra-forma-es-cosa-mayor","status":"publish","type":"wcb_session","link":"https:\/\/madrid.wordcamp.org\/2019\/session\/git-no-es-cosa-menor-dicho-de-otra-forma-es-cosa-mayor\/","title":{"rendered":"Git no es cosa menor, dicho de otra forma: es cosa mayor"},"content":{"rendered":"\n<figure class=\"wp-block-image\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"360\" data-attachment-id=\"3430\" data-permalink=\"https:\/\/madrid.wordcamp.org\/2019\/speaker\/javier-de-juan-trujillo\/03-track-c-javier-de-juan-de-trujillo\/\" data-orig-file=\"https:\/\/i0.wp.com\/madrid.wordcamp.org\/2019\/files\/2019\/04\/03-track-c-javier-de-juan-de-trujillo.jpg?fit=1920%2C1080&amp;ssl=1\" data-orig-size=\"1920,1080\" data-comments-opened=\"0\" data-image-title=\"03-track-c-javier-de-juan-de-trujillo\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/madrid.wordcamp.org\/2019\/files\/2019\/04\/03-track-c-javier-de-juan-de-trujillo.jpg?fit=640%2C360&amp;ssl=1\" src=\"https:\/\/i0.wp.com\/2019.madrid.wordcamp.org\/files\/2019\/04\/03-track-c-javier-de-juan-de-trujillo.jpg?resize=640%2C360&#038;ssl=1\" alt=\"\" class=\"wp-image-3430\" srcset=\"https:\/\/i0.wp.com\/madrid.wordcamp.org\/2019\/files\/2019\/04\/03-track-c-javier-de-juan-de-trujillo.jpg?w=1920&amp;ssl=1 1920w, https:\/\/i0.wp.com\/madrid.wordcamp.org\/2019\/files\/2019\/04\/03-track-c-javier-de-juan-de-trujillo.jpg?resize=300%2C169&amp;ssl=1 300w, https:\/\/i0.wp.com\/madrid.wordcamp.org\/2019\/files\/2019\/04\/03-track-c-javier-de-juan-de-trujillo.jpg?resize=768%2C432&amp;ssl=1 768w, https:\/\/i0.wp.com\/madrid.wordcamp.org\/2019\/files\/2019\/04\/03-track-c-javier-de-juan-de-trujillo.jpg?resize=1024%2C576&amp;ssl=1 1024w, https:\/\/i0.wp.com\/madrid.wordcamp.org\/2019\/files\/2019\/04\/03-track-c-javier-de-juan-de-trujillo.jpg?resize=500%2C281&amp;ssl=1 500w, https:\/\/i0.wp.com\/madrid.wordcamp.org\/2019\/files\/2019\/04\/03-track-c-javier-de-juan-de-trujillo.jpg?w=1280&amp;ssl=1 1280w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Descripci\u00f3n<\/strong>: Ser\u00e9 sincero, a m\u00ed tampoco me ense\u00f1aron GIT bien. Si lo piensas, todo equipo de desarrollo trabaja con un framework, unas best practices, una gu\u00eda de estilos o, al menos, unas normas no escritas pero&#8230; \u00bfqu\u00e9 pasa con GIT? <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mediante un caso pr\u00e1ctico aprenderemos a generar una estrategia de trabajo para GIT que nos permita iniciar un proyecto de manera ordenada y limpia, creando unos h\u00e1bitos que quiz\u00e1s no sab\u00edas que deb\u00edas tener o que nunca te hab\u00edan contado. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Una vez tengamos la estrategia la aplicaremos para la creaci\u00f3n de un plugin para WordPress y, s\u00ed, tambi\u00e9n veremos algunos trucos para sacarle m\u00e1s partido a GIT y resolveremos problemas reales que pueden pasarte en tu d\u00eda a d\u00eda. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00bfA\u00fan te lo est\u00e1s pensando? Al final del taller, aparte de lo aprendido, podr\u00e1s descargarte el plugin sobre el que habremos trabajado y que aportar\u00e1 valor a todos tus proyectos! \u00bfTe apuntas?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Qu\u00e9 aprender\u00e1n en el taller<\/strong>: <\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Generar una estrategia para un proyecto de desarrollo. <\/li><li>Establecer un flujo de GIT. <\/li><li>Establecer un convenio de ramas. <\/li><li>Generar un est\u00e1ndar de commits. <\/li><li>Trabajar con git aliases. <\/li><li>Comandos avanzados de GIT: squash, git log, merge, rebase, tags. <\/li><li>Resolver merge conflicts<\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Nivel del asistente:<\/strong>&nbsp;Avanzado<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>P\u00fablico objetivo:<\/strong>&nbsp;General, Desarrollo<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Descripci\u00f3n: Ser\u00e9 sincero, a m\u00ed tampoco me ense\u00f1aron GIT bien. Si lo piensas, todo equipo de desarrollo trabaja con un framework, unas best practices, una gu\u00eda de estilos o, al menos, unas normas no escritas pero&#8230; \u00bfqu\u00e9 pasa con GIT? Mediante un caso pr\u00e1ctico aprenderemos a generar una estrategia de trabajo para GIT que nos [&hellip;]<\/p>\n","protected":false},"author":16807759,"featured_media":0,"template":"","meta":{"_wcpt_session_time":1554546300,"_wcpt_session_duration":3000,"_wcpt_session_type":"session","_wcpt_session_slides":"","_wcpt_session_video":"","_wcpt_speaker_id":[1877],"footnotes":""},"session_track":[909750],"session_category":[1260310],"class_list":["post-2174","wcb_session","type-wcb_session","status-publish","hentry","wcb_track-talleres","wcb_session_category-desarrollo-sysadmin"],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pheMLx-z4","session_date_time":{"date":"6 abril, 2019","time":"12:25"},"session_speakers":[{"id":"1877","slug":"javier-de-juan-trujillo","name":"Javier De Juan Trujillo","link":"https:\/\/madrid.wordcamp.org\/2019\/speaker\/javier-de-juan-trujillo\/"}],"session_cats_rendered":"Desarrollo","_links":{"self":[{"href":"https:\/\/madrid.wordcamp.org\/2019\/wp-json\/wp\/v2\/sessions\/2174","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/madrid.wordcamp.org\/2019\/wp-json\/wp\/v2\/sessions"}],"about":[{"href":"https:\/\/madrid.wordcamp.org\/2019\/wp-json\/wp\/v2\/types\/wcb_session"}],"version-history":[{"count":8,"href":"https:\/\/madrid.wordcamp.org\/2019\/wp-json\/wp\/v2\/sessions\/2174\/revisions"}],"predecessor-version":[{"id":3540,"href":"https:\/\/madrid.wordcamp.org\/2019\/wp-json\/wp\/v2\/sessions\/2174\/revisions\/3540"}],"speakers":[{"embeddable":true,"href":"https:\/\/madrid.wordcamp.org\/2019\/wp-json\/wp\/v2\/speakers\/1877"}],"author":[{"embeddable":true,"href":"https:\/\/madrid.wordcamp.org\/2019\/wp-json\/wporg\/v1\/users\/javierdejuan"}],"wp:attachment":[{"href":"https:\/\/madrid.wordcamp.org\/2019\/wp-json\/wp\/v2\/media?parent=2174"}],"wp:term":[{"taxonomy":"wcb_track","embeddable":true,"href":"https:\/\/madrid.wordcamp.org\/2019\/wp-json\/wp\/v2\/session_track?post=2174"},{"taxonomy":"wcb_session_category","embeddable":true,"href":"https:\/\/madrid.wordcamp.org\/2019\/wp-json\/wp\/v2\/session_category?post=2174"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}