{"id":2096,"date":"2019-02-19T01:21:49","date_gmt":"2019-02-19T00:21:49","guid":{"rendered":"https:\/\/2019.madrid.wordcamp.org\/?post_type=wcb_speaker&#038;p=2096"},"modified":"2019-06-19T09:45:14","modified_gmt":"2019-06-19T07:45:14","slug":"marta-rey","status":"publish","type":"wcb_speaker","link":"https:\/\/madrid.wordcamp.org\/2019\/speaker\/marta-rey\/","title":{"rendered":"Marta Rey"},"content":{"rendered":"\r\n<p class=\"wp-block-paragraph\">FrontEnder de profesi\u00f3n, dise\u00f1adora de vocaci\u00f3n. Llevo en el mundo del dise\u00f1o web desde 2007. Advenediza de WordPress y usuaria desde 2013, esta es mi primera participaci\u00f3n activa en la Comunidad.<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Soy una apasionada de SASS y de las metodolog\u00edas CSS, la optimizaci\u00f3n es mucho m\u00e1s que minificar archivos. Actualmente trabajo como FrontEnd Web Designer en UNIR.<\/p>\r\n\r\n\r\n\r\n<figure class=\"wp-block-image\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"360\" data-attachment-id=\"3390\" data-permalink=\"https:\/\/madrid.wordcamp.org\/2019\/speaker\/pablo-lopez\/03-track-a-pablo-lopez-marta-rey\/\" data-orig-file=\"https:\/\/i0.wp.com\/madrid.wordcamp.org\/2019\/files\/2019\/04\/03-track-a-pablo-lopez-marta-rey.jpg?fit=1920%2C1080&amp;ssl=1\" data-orig-size=\"1920,1080\" data-comments-opened=\"0\" data-image-title=\"03-track-a-pablo-lopez-marta-rey\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/madrid.wordcamp.org\/2019\/files\/2019\/04\/03-track-a-pablo-lopez-marta-rey.jpg?fit=640%2C360&amp;ssl=1\" class=\"wp-image-3390\" src=\"https:\/\/i0.wp.com\/2019.madrid.wordcamp.org\/files\/2019\/04\/03-track-a-pablo-lopez-marta-rey.jpg?resize=640%2C360&#038;ssl=1\" alt=\"\" srcset=\"https:\/\/i0.wp.com\/madrid.wordcamp.org\/2019\/files\/2019\/04\/03-track-a-pablo-lopez-marta-rey.jpg?w=1920&amp;ssl=1 1920w, https:\/\/i0.wp.com\/madrid.wordcamp.org\/2019\/files\/2019\/04\/03-track-a-pablo-lopez-marta-rey.jpg?resize=300%2C169&amp;ssl=1 300w, https:\/\/i0.wp.com\/madrid.wordcamp.org\/2019\/files\/2019\/04\/03-track-a-pablo-lopez-marta-rey.jpg?resize=768%2C432&amp;ssl=1 768w, https:\/\/i0.wp.com\/madrid.wordcamp.org\/2019\/files\/2019\/04\/03-track-a-pablo-lopez-marta-rey.jpg?resize=1024%2C576&amp;ssl=1 1024w, https:\/\/i0.wp.com\/madrid.wordcamp.org\/2019\/files\/2019\/04\/03-track-a-pablo-lopez-marta-rey.jpg?resize=500%2C281&amp;ssl=1 500w, https:\/\/i0.wp.com\/madrid.wordcamp.org\/2019\/files\/2019\/04\/03-track-a-pablo-lopez-marta-rey.jpg?w=1280&amp;ssl=1 1280w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/figure>\r\n","protected":false},"excerpt":{"rendered":"<p>FrontEnder de profesi\u00f3n, dise\u00f1adora de vocaci\u00f3n. Llevo en el mundo del dise\u00f1o web desde 2007. Advenediza de WordPress y usuaria desde 2013, esta es mi primera participaci\u00f3n activa en la Comunidad. Soy una apasionada de SASS y de las metodolog\u00edas CSS, la optimizaci\u00f3n es mucho m\u00e1s que minificar archivos. Actualmente trabajo como FrontEnd Web Designer [&hellip;]<\/p>\n","protected":false},"author":15898191,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_wcpt_user_name":"martarey","footnotes":""},"speaker_group":[],"class_list":["post-2096","wcb_speaker","type-wcb_speaker","status-publish","hentry"],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pheMLx-xO","avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/6ddf4905e76ea1e4ddd7ad985f844bb1c47eb14fab79b21fb9caa812beb09592?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/6ddf4905e76ea1e4ddd7ad985f844bb1c47eb14fab79b21fb9caa812beb09592?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/6ddf4905e76ea1e4ddd7ad985f844bb1c47eb14fab79b21fb9caa812beb09592?s=96&d=mm&r=g","128":"https:\/\/secure.gravatar.com\/avatar\/6ddf4905e76ea1e4ddd7ad985f844bb1c47eb14fab79b21fb9caa812beb09592?s=128&d=mm&r=g","256":"https:\/\/secure.gravatar.com\/avatar\/6ddf4905e76ea1e4ddd7ad985f844bb1c47eb14fab79b21fb9caa812beb09592?s=256&d=mm&r=g","512":"https:\/\/secure.gravatar.com\/avatar\/6ddf4905e76ea1e4ddd7ad985f844bb1c47eb14fab79b21fb9caa812beb09592?s=512&d=mm&r=g"},"_links":{"self":[{"href":"https:\/\/madrid.wordcamp.org\/2019\/wp-json\/wp\/v2\/speakers\/2096","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/madrid.wordcamp.org\/2019\/wp-json\/wp\/v2\/speakers"}],"about":[{"href":"https:\/\/madrid.wordcamp.org\/2019\/wp-json\/wp\/v2\/types\/wcb_speaker"}],"author":[{"embeddable":true,"href":"https:\/\/madrid.wordcamp.org\/2019\/wp-json\/wp\/v2\/users\/15898191"}],"replies":[{"embeddable":true,"href":"https:\/\/madrid.wordcamp.org\/2019\/wp-json\/wp\/v2\/comments?post=2096"}],"version-history":[{"count":5,"href":"https:\/\/madrid.wordcamp.org\/2019\/wp-json\/wp\/v2\/speakers\/2096\/revisions"}],"predecessor-version":[{"id":3874,"href":"https:\/\/madrid.wordcamp.org\/2019\/wp-json\/wp\/v2\/speakers\/2096\/revisions\/3874"}],"sessions":[{"embeddable":true,"href":"https:\/\/madrid.wordcamp.org\/2019\/wp-json\/wp\/v2\/sessions\/2111?_embed=1&context=view"}],"wp:attachment":[{"href":"https:\/\/madrid.wordcamp.org\/2019\/wp-json\/wp\/v2\/media?parent=2096"}],"wp:term":[{"taxonomy":"wcb_speaker_group","embeddable":true,"href":"https:\/\/madrid.wordcamp.org\/2019\/wp-json\/wp\/v2\/speaker_group?post=2096"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}