{"id":2385,"date":"2025-01-16T20:55:34","date_gmt":"2025-01-16T19:55:34","guid":{"rendered":"https:\/\/madrid.wordcamp.org\/2025\/?p=2385"},"modified":"2025-01-16T20:55:34","modified_gmt":"2025-01-16T19:55:34","slug":"descuento-para-viajar-en-renfe","status":"publish","type":"post","link":"https:\/\/madrid.wordcamp.org\/2025\/blog\/descuento-para-viajar-en-renfe\/","title":{"rendered":"Descuento para viajar en Renfe"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Viendo el ritmo de venta que llevan las entradas para WordCamp Madrid 2025, damos por hecho que te gusta <strong>preparar tu viaje con antelaci\u00f3n<\/strong>, no solo para poder organizarte mejor, sino para obtener los <strong>mejores precios<\/strong> a la hora de reservar tu medio de transporte y alojamiento en Madrid.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Descuento para tu viaje en Renfe<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">En esta ocasi\u00f3n, nuestro equipo de organizaci\u00f3n se ha puesto en contacto con Renfe para negociar un <strong>descuento<\/strong> del que pudieran disfrutar los asistentes a WordCamp Madrid 2025.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Este descuento, es <strong>aplicable sobre cualquier tarifa<\/strong> de venta al p\u00fablico que tenga Renfe ofertada en su web (B\u00e1sico, Elige, Elige Confort y Pr\u00e9mium), por lo que ser\u00e1 aprovechada por muchos m\u00e1s asistentes.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">\u00bfC\u00f3mo canjear el descuento de Renfe?<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Beneficiarte del <strong>5% de descuento<\/strong> es muy sencillo, y \u00fanicamente deber\u00e1s seguir estos pasos a la hora de comprar tu billete en la <a rel=\"noreferrer noopener\" href=\"https:\/\/renfe.es\" data-type=\"URL\" data-id=\"https:\/\/renfe.es\" target=\"_blank\">web de renfe<\/a>.<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li>Selecciona el tren que desees, marcando&nbsp;<strong>en cualquiera de las opciones disponibles (B\u00e1sico, Elige, Elige Confort y Pr\u00e9miun)<\/strong>.<\/li>\n\n\n\n<li>En el desplegable de tarifas selecciona la tarifa de Congresos\/Eventos.<\/li>\n\n\n\n<li>Introduce el n\u00famero de autorizaci\u00f3n (te lo hemos enviado <strong>en el email de confirmaci\u00f3n de compra<\/strong> de tu entrada) en la casilla que indica&nbsp;<strong>n\u00famero de autorizaci\u00f3n<\/strong>. (Este c\u00f3digo no es v\u00e1lido para la casilla \u00abc\u00f3digo descuento\u00bb).<\/li>\n<\/ol>\n\n\n\n<p class=\"wp-block-paragraph\">Al introducir el c\u00f3digo de autorizaci\u00f3n <strong>el precio del billete se reducir\u00e1<\/strong> en un 5% en la p\u00e1gina de compra, aunque no lo veas detallado espec\u00edficamente.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Si tienes cualquier dificultad para canjear el cup\u00f3n, <a href=\"https:\/\/www.renfe.com\/es\/es\/viajar\/prepara-tu-viaje\/descuentos\/congresos-y-eventos\/tutorial.html\" data-type=\"URL\" data-id=\"https:\/\/www.renfe.com\/es\/es\/viajar\/prepara-tu-viaje\/descuentos\/congresos-y-eventos\/tutorial.html\" target=\"_blank\" rel=\"noreferrer noopener\">puedes seguir los pasos de este tutorial.<\/a><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Condiciones del descuento<\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li>V\u00e1lido para compra de billetes por internet o mediante la presentaci\u00f3n de este documento impreso en cualquier punto de venta Renfe (estaciones con venta presencial y agencias de viaje).<\/li>\n\n\n\n<li>Podr\u00e1s obtener billetes en recorridos nacionales de ida y\/o iegreso con origen y destino en las estaciones Madrid Atocha, Madrid-Chamart\u00edn-Clara Campoamor, Madrid-Puerta de Atocha-Almudena Grandes. <strong>Solo AVE-Larga distancia<\/strong>.<\/li>\n\n\n\n<li>Las fechas del viaje tienen que estar comprendidas entre el 5 y el 10 de marzo de 2025.<\/li>\n\n\n\n<li>No est\u00e1n autorizadas las paradas en ruta, salvo en los casos obligados por cambio de tren.<\/li>\n\n\n\n<li>La autorizaci\u00f3n, impresa o PDF en el m\u00f3vil, ser\u00e1 mostrada tanto en control de acceso como al Interventor\/Supervisor del tren junto al billete, siendo obligatorio llevarlo durante todo el recorrido.<\/li>\n\n\n\n<li>No acumulable a ninguna otra oferta comercial, como la tarifa ida\/vuelta.<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\">Guarda tu Autorizaci\u00f3n<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">En el email de confirmaci\u00f3n de compra de tu entrada, te hemos proporcionado el enlace para descargar el PDF con la autorizaci\u00f3n de Renfe, que <strong>deber\u00e1s llevar contigo<\/strong> durante todo el recorrido.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Si la compra de tus billetes la realizas personalmente en una estaci\u00f3n o en una agencia de viajes, deber\u00e1s mostrarles el documento con la autorizaci\u00f3n para que puedan aplicarte el descuento.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Adem\u00e1s, esta autorizaci\u00f3n deber\u00e1 ser mostrada, junto con tu billete, al personal de Renfe siempre que te lo soliciten (control de acceso, interventor o supervisor).<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Incidencias con la autorizaci\u00f3n<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Si por alg\u00fan motivo no has recibido el c\u00f3digo de la autorizaci\u00f3n o el enlace para descargar el PDF <strong>en el email de confirmaci\u00f3n de compra<\/strong> de tu entrada, por favor, cumplimenta este formulario para que podamos comprobarlo y subsanarlo cuanto antes.<\/p>\n\n\n<div data-test='contact-form'\n\t\t\tid='contact-form-2385'\n\t\t\tclass='jetpack-contact-form-container '\n\t\t\tdata-wp-interactive='jetpack\/form' data-wp-context='{\"formId\":\"2385\",\"formHash\":\"197ac6290eae6ace1a972b6fef22f57a6317e640\",\"showErrors\":false,\"errors\":[],\"fields\":[],\"isMultiStep\":false,\"useAjax\":true,\"submissionData\":null,\"formattedSubmissionData\":[],\"submissionSuccess\":false,\"submissionError\":null,\"elementId\":\"jp-form-197ac6290eae6ace1a972b6fef22f57a6317e640\",\"isSingleInputForm\":false,\"isForcedHorizontal\":false}'\n\t\t\tdata-wp-on--focusin=\"actions.trackFirstInteraction\"\n\t\t\tdata-wp-watch--scroll-to-wrapper=\"callbacks.scrollToWrapper\"\n\t\t>\n<div class=\"contact-form-submission contact-form-ajax-submission\" data-wp-bind--aria-hidden=\"state.isSuccessMessageAriaHidden\" data-wp-class--submission-success=\"context.submissionSuccess\" id=\"contact-form-success-197ac6290eae6ace1a972b6fef22f57a6317e640\" tabindex=\"-1\" aria-labelledby=\"contact-form-success-header-197ac6290eae6ace1a972b6fef22f57a6317e640\"><p class=\"go-back-message\"><a class=\"link\" role=\"button\" tabindex=\"0\" data-wp-on--click=\"actions.goBack\" href=\"\/2025\/wp-json\/wp\/v2\/posts\/2385\">\u2190 Back<\/a><\/p><h4 data-wp-bind--aria-hidden=\"state.isSuccessMessageAriaHidden\" id=\"contact-form-success-header-197ac6290eae6ace1a972b6fef22f57a6317e640\">\u00a1Recibido, nos ponemos con ello!<\/h4>\n\n<div class=\"jetpack_forms_contact-form-custom-success-message\">Por favor, permanece atento\/a a tu correo.\n\nUna vez realizadas las comprobaciones necesasrias, te enviaremos un email con el c\u00f3digo de autorizaci\u00f3n y el PDF que deber\u00e1s imprimir y portar durante todo el trayecto en Renfe.<\/div><\/div><form action='https:\/\/madrid.wordcamp.org\/2025\/blog\/descuento-para-viajar-en-renfe\/'\n\t\t\t\tid='jp-form-197ac6290eae6ace1a972b6fef22f57a6317e640'\n\t\t\t\tmethod='post'\n\t\t\t\tclass='contact-form commentsblock jetpack-contact-form__form has-no-jetpack-form-layout' aria-label=\"Descuento para viajar en Renfe\"\n\t\t\t\tdata-wp-on--submit=\"actions.onFormSubmit\"\n\t\t\t\tdata-wp-on--reset=\"actions.onFormReset\"\n\t\t\t\tdata-wp-class--submission-success=\"context.submissionSuccess\"\n\t\t\t\tdata-wp-class--is-first-step=\"state.isFirstStep\"\n\t\t\t\tdata-wp-class--is-last-step=\"state.isLastStep\"\n\t\t\t\tdata-wp-class--is-ajax-form=\"context.useAjax\"\n\t\t\t\tnovalidate >\n<input type='hidden' name='jetpack_contact_form_jwt' value='eyJ0eXAiOiJKV1QiLCJhbGciOiJIUzI1NiJ9.eyJlbmNyeXB0ZWRfYXR0cmlidXRlcyI6Ijl5dW1XMHJyYWV2bXdGaEN4dVJSUmtQQlo0TXVhSE56dmlzMGQrL25kWmFmR0ZNY3g5K1lJRU8veFVIRitwNkw3TUk0RDNxM0Z5SzVwSEFaeWRHSW5wREUwUXpiRUNvcUpNUHUrNmVnZ2ZpYURjVUNYSnA5cG5xLzJnOHhMNEF1YUpZc1RNQ2RDWGFFQUJJRmdsM0gzOFF5QmFtUU5XZDhUNGlObkIvNUVjbUxzK0RqOUsrSnZyc0FBNGNSVXJ6Sk5NanAxZWZUQ1J2SDFObDQxZHJyRFVKZHBhb0UzSGgrZFZTd2hHb2J2ZWJUTU1CTXFlUTdBQWFYYU5nU3FKeldxTjdLdTFzK0oyREU4WG1tbkRiNm0wY0lGUm93dUVmZlROVVpCSXhITXhNb1ZIajU3MUF3aWxMOHBQT0VkaHN2amdpK0dJc05XUVFaRHBNd09OLzhyOTZCZVdiSE5ickNLZ2p1N0FMb0FCZTJUakIvdFBaTzJOZWt2YUwxWkcxMzk3TmFvNWIyaEw1REJjUlpjVGFqM3R6anZDL3RUYkJqUWZrS2o2VnIxcElSNWQ4eG9maGhDaExSNHlVVE1VUStHYnlPT3dtdFBON0I1N2dNN09HR3NiQ3RPNW5LNi91REFZYmsyMTZFMjBkZnI4VGE5WW1GcTAyUDVnUjFTaHAyNzV1VVIxUDhVYVErMTVOOENJL3liTldIZ2tGaDRJMFlJMXowT05pSE5uZWZiNGdoclJ4MEdiVTFsRGFxUHdBbGVsTFNuY200U0JqQ3lpS1g5U2NIVGdtOGVXczhQWWRYNzFaNW5LVVNYazI2UWVuTXhGOVdteXBFT1Y1WmIvaDQ0N3hXV2JLcy9ZSitLRmd2VkNrQUNvOEJ1dmhQVFdoZ3c5WTZ3TitTT094dndMUWhicHV0M1VrdjM0M0QvSUFMNFkrdlVva1dYcFZTeTgyU2Y2bU1uZVhUdEFkaGdEWmlKd2IycE9CQ2FVY3d6V2c2dnh2T2lGMS95eTZhZjI1c0lNUWl4ZE5JY2JWS3pwYmE1WXhyZlc0NDI4K0laaXdUNHJwSFdFYVZTK1VVUTNhVlR1RUhoSjNsd2tJVnZwU0E2bFczTWNRbWMvOWJaOHhTcnltck16NkdwTDBVdENtQmVIMS9wZUNuZFFUS2h0STF1UXdEajBiSEFSbUFkVXZjVzhjY1h2VVBzUTNObDJkemdNcko1NDllU0JKUnE4bzBHTldpcGltV2ZtTGI2aWJIQXE2UXF6M1BqbCtOTW5oZmVvTHZLRGlTOS9jZ1h5U2wxTE1JYkUrOENkL1kxVnFPNVlrVko1MHpqZmlDSmx4WE5KRmk2aVBPbUlhTHhwbUdXUkJXTTlsMlZDOUpaSllUbzFXT3JGTGk3akp0V3BhcnlVQk5NdjFmcUlQU3dxOUluSi9sWGZFZjBHVVNZMy81YTEvK2V1Q1FFTDJuMGVkdG5HZG90eVhLeDRGeWJUNjE1U3k1UUxOaTdLSlpBdjQzTGxrWHE0SjJMQ0ZwQSsvbUdOcjQzQjl1NjNOemZXaXlxdnZHbUU4VHVOaGE0VUlaZXVhMVo0L3VkYUZBME5CRnpFSGZIbXVmRTdscldGSlBmTDROY1lZMGJkYm5MSHBJYWFBTG9pQVh1eExPOHREWmdXOWkiLCJjb250ZW50IjoiXG48ZGl2IGNsYXNzPVwid3AtYmxvY2stamV0cGFjay1jb250YWN0LWZvcm1cIiBzdHlsZT1cInBhZGRpbmctdG9wOjE2cHg7cGFkZGluZy1yaWdodDoxNnB4O3BhZGRpbmctYm90dG9tOjE2cHg7cGFkZGluZy1sZWZ0OjE2cHhcIj5bY29udGFjdC1maWVsZCBsYWJlbD1cIk5vbWJyZSBjb24gZWwgcXVlIGhhcyBjb21wcmFkbyB0dSBlbnRyYWRhXCIgcmVxdWlyZWQ9XCIxXCIgcmVxdWlyZWRUZXh0PVwiKG9ibGlnYXRvcmlvKVwiIHR5cGU9XCJuYW1lXCIvXVxuXG5bY29udGFjdC1maWVsZCBsYWJlbD1cIkNvcnJlbyBlbGVjdHJcdTAwZjNuaWNvIGNvbiBlbCBxdWUgaGFzIGNvbXByYWRvIHR1IGVudHJhZGFcIiByZXF1aXJlZD1cIjFcIiByZXF1aXJlZFRleHQ9XCIob2JsaWdhdG9yaW8pXCIgdHlwZT1cImVtYWlsXCIvXVxuXG5bY29udGFjdC1maWVsZCBsYWJlbD1cIlx1MDBiZlF1XHUwMGU5IG5lY2VzaXRhcz9cIiByZXF1aXJlZFRleHQ9XCIob2JsaWdhdG9yaW8pXCIgdHlwZT1cInRleHRhcmVhXCIvXVxuXG48ZGl2IGNsYXNzPVwid3AtYmxvY2stamV0cGFjay1idXR0b24gd3AtYmxvY2stYnV0dG9uXCIgc3R5bGU9XCJcIj48YnV0dG9uIGNsYXNzPVwid3AtYmxvY2stYnV0dG9uX19saW5rXCIgc3R5bGU9XCJcIiBkYXRhLWlkLWF0dHI9XCJwbGFjZWhvbGRlclwiIHR5cGU9XCJzdWJtaXRcIiBkYXRhLXdwLWNsYXNzLS1pcy1zdWJtaXR0aW5nPVwic3RhdGUuaXNTdWJtaXR0aW5nXCIgZGF0YS13cC1iaW5kLS1hcmlhLWRpc2FibGVkPVwic3RhdGUuaXNBcmlhRGlzYWJsZWRcIj5FbnZpYXIgSW5jaWRlbmNpYTxzcGFuIGNsYXNzPVwic3Bpbm5lclwiIGFyaWEtaGlkZGVuPVwidHJ1ZVwiPjxzdmcgd2lkdGg9XCIyNFwiIGhlaWdodD1cIjI0XCIgdmlld0JveD1cIjAgMCAyNCAyNFwiIHhtbG5zPVwiaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmdcIj48cGF0aCBkPVwiTTEyLDFBMTEsMTEsMCwxLDAsMjMsMTIsMTEsMTEsMCwwLDAsMTIsMVptMCwxOWE4LDgsMCwxLDEsOC04QTgsOCwwLDAsMSwxMiwyMFpcIiBvcGFjaXR5PVwiLjI1XCIvPjxwYXRoIGQ9XCJNMTAuMTQsMS4xNmExMSwxMSwwLDAsMC05LDguOTJBMS41OSwxLjU5LDAsMCwwLDIuNDYsMTIsMS41MiwxLjUyLDAsMCwwLDQuMTEsMTAuN2E4LDgsMCwwLDEsNi42Ni02LjYxQTEuNDIsMS40MiwwLDAsMCwxMiwyLjY5aDBBMS41NywxLjU3LDAsMCwwLDEwLjE0LDEuMTZaXCI-PGFuaW1hdGVUcmFuc2Zvcm0gYXR0cmlidXRlTmFtZT1cInRyYW5zZm9ybVwiIHR5cGU9XCJyb3RhdGVcIiBkdXI9XCIwLjc1c1wiIHZhbHVlcz1cIjAgMTIgMTI7MzYwIDEyIDEyXCIgcmVwZWF0Q291bnQ9XCJpbmRlZmluaXRlXCIvPjwvcGF0aD48L3N2Zz48c3BhbiBjbGFzcz1cImlzLXZpc3VhbGx5LWhpZGRlblwiPlN1Ym1pdHRpbmcgZm9ybTwvc3Bhbj48L3NwYW4-PC9idXR0b24-PC9kaXY-PC9kaXY-XG4iLCJoYXNoIjoiMTk3YWM2MjkwZWFlNmFjZTFhOTcyYjZmZWYyMmY1N2E2MzE3ZTY0MCIsInNvdXJjZSI6eyJlbnRyeV90aXRsZSI6IkRlc2N1ZW50byBwYXJhIHZpYWphciBlbiBSZW5mZSIsImVudHJ5X3BhZ2UiOjEsInNvdXJjZV9pZCI6MjM4NSwic291cmNlX3R5cGUiOiJzaW5nbGUiLCJyZXF1ZXN0X3VybCI6Imh0dHBzOi8vbWFkcmlkLndvcmRjYW1wLm9yZy8yMDI1L3dwLWpzb24vd3AvdjIvcG9zdHMvMjM4NSJ9LCJ2ZXJzaW9uIjoyLCJjaXBoZXIiOiJhZXMtMjU2LWdjbSJ9.HcvQry8EV-10DqDgHqb5A3fdFfGMd1y0vSYmRGWjgEg' \/>\n<input type='hidden' name='jetpack_form_fill_duration' value='' \/>\n\n<div class=\"wp-block-jetpack-contact-form is-layout-flex wp-container-jetpack-contact-form-is-layout-53c17e14 wp-block-jetpack-contact-form-is-layout-flex\" style=\"padding-top:16px;padding-right:16px;padding-bottom:16px;padding-left:16px\">\n<div style=\"\"  data-wp-interactive=\"jetpack\/form\" data-wp-context='{\"fieldId\":\"g2385-nombreconelquehascompradotuentrada\",\"fieldType\":\"name\",\"fieldLabel\":\"Nombre con el que has comprado tu entrada\",\"fieldValue\":\"\",\"fieldPlaceholder\":\"\",\"fieldIsRequired\":\"1\",\"fieldErrorMessage\":\"\",\"fieldExtra\":[],\"formHash\":\"197ac6290eae6ace1a972b6fef22f57a6317e640\"}'  class='grunion-field-name-wrap grunion-field-wrap'  data-wp-init='callbacks.initializeField' data-wp-on--jetpack-form-reset='callbacks.initializeField' >\n<label\n\t\t\t\tfor='g2385-nombreconelquehascompradotuentrada' class=\"grunion-field-label name\" >Nombre con el que has comprado tu entrada<span class=\"grunion-label-required\" aria-hidden=\"true\">(obligatorio)<\/span><\/label>\n<input\n\t\t\t\t\ttype='text'\n\t\t\t\t\tname='g2385-nombreconelquehascompradotuentrada'\n\t\t\t\t\tid='g2385-nombreconelquehascompradotuentrada'\n\t\t\t\t\tvalue=''\n\n\t\t\t\t\tdata-wp-bind--aria-invalid='state.fieldAriaInvalid'\n\t\t\t\t\tdata-wp-bind--value='state.getFieldValue'\n\t\t\t\t\taria-describedby='g2385-nombreconelquehascompradotuentrada-text-error-message'\n\t\t\t\t\tdata-wp-on--input='actions.onFieldChange'\n\t\t\t\t\tdata-wp-on--blur='actions.onFieldBlur'\n\t\t\t\t\tdata-wp-class--has-value='state.hasFieldValue'\n\n\t\t\t\t\tclass='name  grunion-field' \n\t\t\t\t\trequired='true' aria-required='true'  \/>\n \n\t\t\t<div id=\"g2385-nombreconelquehascompradotuentrada-text-error\" class=\"contact-form__input-error\" data-wp-class--has-errors=\"state.fieldHasErrors\">\n\t\t\t\t<span class=\"contact-form__warning-icon\" aria-hidden=\"true\">\n\t\t\t\t\t<svg width=\"16\" height=\"16\" viewBox=\"0 0 16 16\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n\t\t\t\t\t\t<path d=\"M8.50015 11.6402H7.50015V10.6402H8.50015V11.6402Z\" \/>\n\t\t\t\t\t\t<path d=\"M7.50015 9.64018H8.50015V6.30684H7.50015V9.64018Z\" \/>\n\t\t\t\t\t\t<path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M6.98331 3.0947C7.42933 2.30177 8.57096 2.30177 9.01698 3.09469L13.8771 11.7349C14.3145 12.5126 13.7525 13.4735 12.8602 13.4735H3.14004C2.24774 13.4735 1.68575 12.5126 2.12321 11.7349L6.98331 3.0947ZM8.14541 3.58496C8.08169 3.47168 7.9186 3.47168 7.85488 3.58496L2.99478 12.2251C2.93229 12.3362 3.01257 12.4735 3.14004 12.4735H12.8602C12.9877 12.4735 13.068 12.3362 13.0055 12.2251L8.14541 3.58496Z\" \/>\n\t\t\t\t\t<\/svg>\n\t\t\t\t<\/span>\n\t\t\t\t<span data-wp-text=\"state.errorMessage\" id=\"g2385-nombreconelquehascompradotuentrada-text-error-message\"><\/span>\n\t\t\t<\/div> \n\t<\/div>\n\n\n\n<div style=\"\"  data-wp-interactive=\"jetpack\/form\" data-wp-context='{\"fieldId\":\"g2385-correoelectrnicoconelquehascompradotuentrada\",\"fieldType\":\"email\",\"fieldLabel\":\"Correo electr\\u00f3nico con el que has comprado tu entrada\",\"fieldValue\":\"\",\"fieldPlaceholder\":\"\",\"fieldIsRequired\":\"1\",\"fieldErrorMessage\":\"\",\"fieldExtra\":[],\"formHash\":\"197ac6290eae6ace1a972b6fef22f57a6317e640\"}'  class='grunion-field-email-wrap grunion-field-wrap'  data-wp-init='callbacks.initializeField' data-wp-on--jetpack-form-reset='callbacks.initializeField' >\n<label\n\t\t\t\tfor='g2385-correoelectrnicoconelquehascompradotuentrada' class=\"grunion-field-label email\" >Correo electr\u00f3nico con el que has comprado tu entrada<span class=\"grunion-label-required\" aria-hidden=\"true\">(obligatorio)<\/span><\/label>\n<input\n\t\t\t\t\ttype='email'\n\t\t\t\t\tname='g2385-correoelectrnicoconelquehascompradotuentrada'\n\t\t\t\t\tid='g2385-correoelectrnicoconelquehascompradotuentrada'\n\t\t\t\t\tvalue=''\n\n\t\t\t\t\tdata-wp-bind--aria-invalid='state.fieldAriaInvalid'\n\t\t\t\t\tdata-wp-bind--value='state.getFieldValue'\n\t\t\t\t\taria-describedby='g2385-correoelectrnicoconelquehascompradotuentrada-email-error-message'\n\t\t\t\t\tdata-wp-on--input='actions.onFieldChange'\n\t\t\t\t\tdata-wp-on--blur='actions.onFieldBlur'\n\t\t\t\t\tdata-wp-class--has-value='state.hasFieldValue'\n\n\t\t\t\t\tclass='email  grunion-field' \n\t\t\t\t\trequired='true' aria-required='true'  \/>\n \n\t\t\t<div id=\"g2385-correoelectrnicoconelquehascompradotuentrada-email-error\" class=\"contact-form__input-error\" data-wp-class--has-errors=\"state.fieldHasErrors\">\n\t\t\t\t<span class=\"contact-form__warning-icon\" aria-hidden=\"true\">\n\t\t\t\t\t<svg width=\"16\" height=\"16\" viewBox=\"0 0 16 16\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n\t\t\t\t\t\t<path d=\"M8.50015 11.6402H7.50015V10.6402H8.50015V11.6402Z\" \/>\n\t\t\t\t\t\t<path d=\"M7.50015 9.64018H8.50015V6.30684H7.50015V9.64018Z\" \/>\n\t\t\t\t\t\t<path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M6.98331 3.0947C7.42933 2.30177 8.57096 2.30177 9.01698 3.09469L13.8771 11.7349C14.3145 12.5126 13.7525 13.4735 12.8602 13.4735H3.14004C2.24774 13.4735 1.68575 12.5126 2.12321 11.7349L6.98331 3.0947ZM8.14541 3.58496C8.08169 3.47168 7.9186 3.47168 7.85488 3.58496L2.99478 12.2251C2.93229 12.3362 3.01257 12.4735 3.14004 12.4735H12.8602C12.9877 12.4735 13.068 12.3362 13.0055 12.2251L8.14541 3.58496Z\" \/>\n\t\t\t\t\t<\/svg>\n\t\t\t\t<\/span>\n\t\t\t\t<span data-wp-text=\"state.errorMessage\" id=\"g2385-correoelectrnicoconelquehascompradotuentrada-email-error-message\"><\/span>\n\t\t\t<\/div> \n\t<\/div>\n\n\n\n<div style=\"\"  data-wp-interactive=\"jetpack\/form\" data-wp-context='{\"fieldId\":\"g2385-qunecesitas\",\"fieldType\":\"textarea\",\"fieldLabel\":\"\\u00bfQu\\u00e9 necesitas?\",\"fieldValue\":\"\",\"fieldPlaceholder\":\"\",\"fieldIsRequired\":\"\",\"fieldErrorMessage\":\"\",\"fieldExtra\":[],\"formHash\":\"197ac6290eae6ace1a972b6fef22f57a6317e640\"}'  class='grunion-field-textarea-wrap grunion-field-wrap'  data-wp-init='callbacks.initializeField' data-wp-on--jetpack-form-reset='callbacks.initializeField' >\n<label\n\t\t\t\tfor='contact-form-comment-g2385-qunecesitas' class=\"grunion-field-label textarea\" >\u00bfQu\u00e9 necesitas?<\/label>\n<textarea\n\t\t                style=''\n\t\t                name='g2385-qunecesitas'\n\t\t                id='contact-form-comment-g2385-qunecesitas'\n\t\t                rows='20'\n\t\t\t\t\t\tdata-wp-text='state.getFieldValue'\n\t\t\t\t\t\tdata-wp-on--input='actions.onFieldChange'\n\t\t\t\t\t\tdata-wp-on--blur='actions.onFieldBlur'\n\t\t\t\t\t\tdata-wp-class--has-value='state.hasFieldValue'\n\t\t\t\t\t\taria-describedby='g2385-qunecesitas-textarea-error-message'\n\t\t\t\t\t\tdata-wp-bind--aria-invalid='state.fieldAriaInvalid'\n\t\t\t\t\t\tclass='textarea  grunion-field'  ><\/textarea>\n \n\t\t\t<div id=\"g2385-qunecesitas-textarea-error\" class=\"contact-form__input-error\" data-wp-class--has-errors=\"state.fieldHasErrors\">\n\t\t\t\t<span class=\"contact-form__warning-icon\" aria-hidden=\"true\">\n\t\t\t\t\t<svg width=\"16\" height=\"16\" viewBox=\"0 0 16 16\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n\t\t\t\t\t\t<path d=\"M8.50015 11.6402H7.50015V10.6402H8.50015V11.6402Z\" \/>\n\t\t\t\t\t\t<path d=\"M7.50015 9.64018H8.50015V6.30684H7.50015V9.64018Z\" \/>\n\t\t\t\t\t\t<path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M6.98331 3.0947C7.42933 2.30177 8.57096 2.30177 9.01698 3.09469L13.8771 11.7349C14.3145 12.5126 13.7525 13.4735 12.8602 13.4735H3.14004C2.24774 13.4735 1.68575 12.5126 2.12321 11.7349L6.98331 3.0947ZM8.14541 3.58496C8.08169 3.47168 7.9186 3.47168 7.85488 3.58496L2.99478 12.2251C2.93229 12.3362 3.01257 12.4735 3.14004 12.4735H12.8602C12.9877 12.4735 13.068 12.3362 13.0055 12.2251L8.14541 3.58496Z\" \/>\n\t\t\t\t\t<\/svg>\n\t\t\t\t<\/span>\n\t\t\t\t<span data-wp-text=\"state.errorMessage\" id=\"g2385-qunecesitas-textarea-error-message\"><\/span>\n\t\t\t<\/div>\n\t<\/div>\n\n\n<div class=\"contact-form__error\" data-wp-class--show-errors=\"state.showFormErrors\"><span class=\"contact-form__warning-icon\" aria-hidden=\"true\"><i><\/i><\/span><span class=\"contact-form__error-message\" tabindex=\"-1\" data-wp-watch=\"callbacks.focusOnValidationError\" data-wp-text=\"state.getFormErrorMessage\"><\/span><ul aria-label=\"Form errors\">\n\t\t\t\t<template data-wp-each=\"state.getErrorList\" data-wp-key=\"context.item.id\">\n\t\t\t\t\t<li><a data-wp-bind--href=\"context.item.anchor\" data-wp-on--click=\"actions.scrollIntoView\" data-wp-text=\"context.item.label\"><\/a><\/li>\n\t\t\t\t<\/template>\n\t\t\t\t<\/ul><\/div><div class=\"contact-form__error\" data-wp-class--show-errors=\"state.showSubmissionError\" data-wp-text=\"context.submissionError\" tabindex=\"-1\" data-wp-watch=\"callbacks.focusOnSubmissionError\"><\/div> <div class=\"wp-block-jetpack-button wp-block-button\" style=\"\"><button data-wp-bind--disabled=\"state.isAriaDisabled\" class=\"wp-block-button__link\" style=\"\" data-id-attr=\"placeholder\" type=\"submit\" data-wp-class--is-submitting=\"state.isSubmitting\" data-wp-bind--aria-disabled=\"state.isAriaDisabled\">Enviar Incidencia<span class=\"spinner\" aria-hidden=\"true\"><svg width=\"24\" height=\"24\" viewBox=\"0 0 24 24\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M12,1A11,11,0,1,0,23,12,11,11,0,0,0,12,1Zm0,19a8,8,0,1,1,8-8A8,8,0,0,1,12,20Z\" opacity=\".25\"\/><path d=\"M10.14,1.16a11,11,0,0,0-9,8.92A1.59,1.59,0,0,0,2.46,12,1.52,1.52,0,0,0,4.11,10.7a8,8,0,0,1,6.66-6.61A1.42,1.42,0,0,0,12,2.69h0A1.57,1.57,0,0,0,10.14,1.16Z\"><animateTransform attributeName=\"transform\" type=\"rotate\" dur=\"0.75s\" values=\"0 12 12;360 12 12\" repeatCount=\"indefinite\"\/><\/path><\/svg><span class=\"is-visually-hidden\">Submitting form<\/span><\/span><\/button><\/div><\/div>\n\t\t<input type='hidden' name='contact-form-id' value='2385' \/>\n\t\t<input type='hidden' name='action' value='grunion-contact-form' \/>\n\t\t<input type='hidden' name='contact-form-hash' value='197ac6290eae6ace1a972b6fef22f57a6317e640' \/>\n<p style=\"display: none !important;\" class=\"akismet-fields-container\" data-prefix=\"ak_\"><label>&#916;<textarea name=\"ak_hp_textarea\" cols=\"45\" rows=\"8\" maxlength=\"100\"><\/textarea><\/label><input type=\"hidden\" id=\"ak_js_1\" name=\"ak_js\" value=\"105\"\/><script>\ndocument.getElementById( \"ak_js_1\" ).setAttribute( \"value\", ( new Date() ).getTime() );\n<\/script>\n<\/p><\/form>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Si viajas hasta Madrid para asistir a WordCamp 2025 y est\u00e1sn pensando en utilizar el transporte p\u00fablico, tenemos para ti este descuento para viajar en Renfe.<\/p>\n","protected":false},"author":15451467,"featured_media":2388,"comment_status":"closed","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"jetpack_seo_schema_type":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[1],"tags":[],"class_list":["post-2385","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog"],"jetpack-related-posts":[{"id":3,"url":"https:\/\/madrid.wordcamp.org\/2025\/blog\/welcome-to-wordcamp-madrid-comunidad-de-madrid-spain\/","url_meta":{"origin":2385,"position":0},"title":"Bienvenidos a WordCamp Madrid 2025","author":"Juanma Aranda","date":"16\/04\/2024","format":false,"excerpt":"Ha pasado m\u00e1s de un a\u00f1o desde que tuvo lugar la \u00faltima edici\u00f3n de WordCamp Madrid, all\u00e1 por Noviembre de 2023 y, desde entonces, hemos estado trabajando duro, detr\u00e1s de las pantallas, para poderte invitar a una nueva edici\u00f3n del mayor evento de WordPress que se celebra en Espa\u00f1a. Sin\u2026","rel":"","context":"En \u00abBlog\u00bb","block_context":{"text":"Blog","link":"https:\/\/madrid.wordcamp.org\/2025\/category\/blog\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/madrid.wordcamp.org\/2025\/files\/2024\/06\/wcmad23-003-1.jpg?fit=640%2C498&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/madrid.wordcamp.org\/2025\/files\/2024\/06\/wcmad23-003-1.jpg?fit=640%2C498&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/madrid.wordcamp.org\/2025\/files\/2024\/06\/wcmad23-003-1.jpg?fit=640%2C498&ssl=1&resize=525%2C300 1.5x"},"classes":[]},{"id":3745,"url":"https:\/\/madrid.wordcamp.org\/2025\/blog\/cerramos-la-venta-de-entradas\/","url_meta":{"origin":2385,"position":1},"title":"Cerramos la venta de entradas","author":"Juanma Aranda","date":"06\/03\/2025","format":false,"excerpt":"El Jueves 6 de marzo a las 23:59h quedar\u00e1 cerrada la venta de entradas para WordCamp Madrid 2025.","rel":"","context":"En \u00abBlog\u00bb","block_context":{"text":"Blog","link":"https:\/\/madrid.wordcamp.org\/2025\/category\/blog\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/madrid.wordcamp.org\/2025\/files\/2025\/03\/image.png?fit=1024%2C768&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/madrid.wordcamp.org\/2025\/files\/2025\/03\/image.png?fit=1024%2C768&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/madrid.wordcamp.org\/2025\/files\/2025\/03\/image.png?fit=1024%2C768&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/madrid.wordcamp.org\/2025\/files\/2025\/03\/image.png?fit=1024%2C768&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":2118,"url":"https:\/\/madrid.wordcamp.org\/2025\/blog\/te-llevamos-en-bus\/","url_meta":{"origin":2385,"position":2},"title":"Te llevamos en bus","author":"Juanma Aranda","date":"05\/01\/2025","format":false,"excerpt":"Desde la organizaci\u00f3n de WordCamp Madrid 2025 te proporcionamos transporte en bus el s\u00e1bado 8 de marzo para llegar hasta la ubicaci\u00f3n del evento y volver despu\u00e9s.","rel":"","context":"En \u00abBlog\u00bb","block_context":{"text":"Blog","link":"https:\/\/madrid.wordcamp.org\/2025\/category\/blog\/"},"img":{"alt_text":"bus wordcamp madrid 2025","src":"https:\/\/i0.wp.com\/madrid.wordcamp.org\/2025\/files\/2024\/12\/bus-wordcamp-madrid-2025.jpg?fit=1024%2C768&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/madrid.wordcamp.org\/2025\/files\/2024\/12\/bus-wordcamp-madrid-2025.jpg?fit=1024%2C768&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/madrid.wordcamp.org\/2025\/files\/2024\/12\/bus-wordcamp-madrid-2025.jpg?fit=1024%2C768&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/madrid.wordcamp.org\/2025\/files\/2024\/12\/bus-wordcamp-madrid-2025.jpg?fit=1024%2C768&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":3446,"url":"https:\/\/madrid.wordcamp.org\/2025\/blog\/gracias-joinchat\/","url_meta":{"origin":2385,"position":3},"title":"Gracias, Joinchat","author":"Juanma Aranda","date":"28\/02\/2025","format":false,"excerpt":"Gracias, JoinChat, por ser parte de WordCamp Madrid 2025 Gracias, Joinchat, por ser parte de WordCamp Madrid 2025En WordCamp Madrid 2025, estamos agradecidos con Joinchat, nuestro Patrocinador Plata, por su apoyo a la comunidad de WordPress. Con m\u00e1s de 700.000 instalaciones activas Joinchat es un plugin de WordPress que canaliza\u2026","rel":"","context":"En \u00abBlog\u00bb","block_context":{"text":"Blog","link":"https:\/\/madrid.wordcamp.org\/2025\/category\/blog\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/madrid.wordcamp.org\/2025\/files\/2025\/02\/gracias-joinchat.png?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/madrid.wordcamp.org\/2025\/files\/2025\/02\/gracias-joinchat.png?fit=1200%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/madrid.wordcamp.org\/2025\/files\/2025\/02\/gracias-joinchat.png?fit=1200%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/madrid.wordcamp.org\/2025\/files\/2025\/02\/gracias-joinchat.png?fit=1200%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/madrid.wordcamp.org\/2025\/files\/2025\/02\/gracias-joinchat.png?fit=1200%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":1937,"url":"https:\/\/madrid.wordcamp.org\/2025\/blog\/abrimos-llamada-a-patrocinadores\/","url_meta":{"origin":2385,"position":4},"title":"Abrimos llamada a patrocinadores","author":"Angel Zinsel","date":"19\/12\/2024","format":false,"excerpt":"\u00a1Ya puedes reservar tu patrocinio para la mayor WordCamp de Espa\u00f1a! Estamos trabajando intensamente para hacer que WordCamp Madrid 2025 sea a\u00fan mejor que la anterior. Si el a\u00f1o pasado logramos reunir a m\u00e1s de 600 asistentes, este a\u00f1o esperamos superar los 800. ver todos los detalles Tenemos los cl\u00e1sicos\u2026","rel":"","context":"En \u00abBlog\u00bb","block_context":{"text":"Blog","link":"https:\/\/madrid.wordcamp.org\/2025\/category\/blog\/"},"img":{"alt_text":"Llamada a patrocinadores","src":"https:\/\/i0.wp.com\/madrid.wordcamp.org\/2025\/files\/2024\/12\/llamada-a-patrocinadores-wordcamp-madrid-2025-scaled.jpg?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/madrid.wordcamp.org\/2025\/files\/2024\/12\/llamada-a-patrocinadores-wordcamp-madrid-2025-scaled.jpg?fit=1200%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/madrid.wordcamp.org\/2025\/files\/2024\/12\/llamada-a-patrocinadores-wordcamp-madrid-2025-scaled.jpg?fit=1200%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/madrid.wordcamp.org\/2025\/files\/2024\/12\/llamada-a-patrocinadores-wordcamp-madrid-2025-scaled.jpg?fit=1200%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/madrid.wordcamp.org\/2025\/files\/2024\/12\/llamada-a-patrocinadores-wordcamp-madrid-2025-scaled.jpg?fit=1200%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":3428,"url":"https:\/\/madrid.wordcamp.org\/2025\/blog\/gracias-woo\/","url_meta":{"origin":2385,"position":5},"title":"Gracias, woo","author":"Juanma Aranda","date":"07\/03\/2025","format":false,"excerpt":"Agradecimiento a Woo por su apoyo a WordCamp Madrid 2025 En WordCamp Madrid 2025, estamos profundamente agradecidos con\u00a0Woo, nuestro\u00a0Patrocinador Platino, por su invaluable apoyo a la comunidad de WordPress. Woo, la plataforma de comercio electr\u00f3nico l\u00edder para WordPress, ha transformado la forma en que las empresas venden en l\u00ednea, ofreciendo\u2026","rel":"","context":"En \u00abBlog\u00bb","block_context":{"text":"Blog","link":"https:\/\/madrid.wordcamp.org\/2025\/category\/blog\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/madrid.wordcamp.org\/2025\/files\/2025\/02\/gracias-woo.png?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/madrid.wordcamp.org\/2025\/files\/2025\/02\/gracias-woo.png?fit=1200%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/madrid.wordcamp.org\/2025\/files\/2025\/02\/gracias-woo.png?fit=1200%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/madrid.wordcamp.org\/2025\/files\/2025\/02\/gracias-woo.png?fit=1200%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/madrid.wordcamp.org\/2025\/files\/2025\/02\/gracias-woo.png?fit=1200%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pheMBD-Ct","jetpack_featured_media_url":"https:\/\/i0.wp.com\/madrid.wordcamp.org\/2025\/files\/2025\/01\/showing-a-high-speed-train-standing-on-a-station-platform-the.png?fit=1024%2C768&ssl=1","_links":{"self":[{"href":"https:\/\/madrid.wordcamp.org\/2025\/wp-json\/wp\/v2\/posts\/2385","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/madrid.wordcamp.org\/2025\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/madrid.wordcamp.org\/2025\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/madrid.wordcamp.org\/2025\/wp-json\/wp\/v2\/users\/15451467"}],"replies":[{"embeddable":true,"href":"https:\/\/madrid.wordcamp.org\/2025\/wp-json\/wp\/v2\/comments?post=2385"}],"version-history":[{"count":2,"href":"https:\/\/madrid.wordcamp.org\/2025\/wp-json\/wp\/v2\/posts\/2385\/revisions"}],"predecessor-version":[{"id":2389,"href":"https:\/\/madrid.wordcamp.org\/2025\/wp-json\/wp\/v2\/posts\/2385\/revisions\/2389"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/madrid.wordcamp.org\/2025\/wp-json\/wp\/v2\/media\/2388"}],"wp:attachment":[{"href":"https:\/\/madrid.wordcamp.org\/2025\/wp-json\/wp\/v2\/media?parent=2385"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/madrid.wordcamp.org\/2025\/wp-json\/wp\/v2\/categories?post=2385"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/madrid.wordcamp.org\/2025\/wp-json\/wp\/v2\/tags?post=2385"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}