{"id":2606,"date":"2025-02-06T19:03:57","date_gmt":"2025-02-06T18:03:57","guid":{"rendered":"https:\/\/madrid.wordcamp.org\/2025\/?post_type=wcb_session&#038;p=2606"},"modified":"2025-02-07T13:50:52","modified_gmt":"2025-02-07T12:50:52","slug":"microcomunidades-wordpress-la-formula-del-impacto-social-positivo","status":"publish","type":"wcb_session","link":"https:\/\/madrid.wordcamp.org\/2025\/session\/microcomunidades-wordpress-la-formula-del-impacto-social-positivo\/","title":{"rendered":"Microcomunidades + WordPress: La f\u00f3rmula del impacto social positivo"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">La comunidad WordPress ha crecido gracias a meetups y WordCamps, pero hay una nueva tendencia que est\u00e1 marcando la diferencia: las microcomunidades. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Estos peque\u00f1os pero poderosos grupos est\u00e1n logrando un impacto social inesperado, llevando WordPress a nuevas audiencias y prop\u00f3sitos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En esta charla descubrir\u00e1s c\u00f3mo nacen estas microcomunidades, proyectos reales que est\u00e1n transformando vidas a nivel nacional e internacional, y herramientas y estrategias para crear tu propio grupo de impacto. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Aprende c\u00f3mo WordPress puede ser mucho m\u00e1s que un CMS: un catalizador para el cambio social.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Qu\u00e9 aprender\u00e1n los asistentes<\/strong>: Inspiraci\u00f3n real de proyectos positivos, estrategias pr\u00e1cticas para crear microcomunidades, formas de conectar con nuevos p\u00fablicos y un mensaje motivador en tiempos de exceso de drama.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La comunidad WordPress ha crecido gracias a meetups y WordCamps, pero hay una nueva tendencia que est\u00e1 marcando la diferencia: las microcomunidades. Estos peque\u00f1os pero poderosos grupos est\u00e1n logrando un impacto social inesperado, llevando WordPress a nuevas audiencias y prop\u00f3sitos. En esta charla descubrir\u00e1s c\u00f3mo nacen estas microcomunidades, proyectos reales que est\u00e1n transformando vidas a [&hellip;]<\/p>\n","protected":false},"author":14240579,"featured_media":0,"template":"","meta":{"advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"jetpack_seo_schema_type":"","_wcpt_session_time":1741424400,"_wcpt_session_duration":3600,"_wcpt_session_type":"session","_wcpt_session_slides":"","_wcpt_session_video":"","_wcpt_speaker_id":[2544],"footnotes":""},"session_track":[18],"session_category":[25],"class_list":["post-2606","wcb_session","type-wcb_session","status-publish","hentry","wcb_track-aula-magna","wcb_session_category-comunidad"],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pheMBD-G2","session_date_time":{"date":"08\/03\/2025","time":"10:00"},"session_speakers":[{"id":"2544","slug":"juan-hernando","name":"Juan Hernando","link":"https:\/\/madrid.wordcamp.org\/2025\/speaker\/juan-hernando\/"}],"session_cats_rendered":"Comunidad","_links":{"self":[{"href":"https:\/\/madrid.wordcamp.org\/2025\/wp-json\/wp\/v2\/sessions\/2606","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/madrid.wordcamp.org\/2025\/wp-json\/wp\/v2\/sessions"}],"about":[{"href":"https:\/\/madrid.wordcamp.org\/2025\/wp-json\/wp\/v2\/types\/wcb_session"}],"version-history":[{"count":2,"href":"https:\/\/madrid.wordcamp.org\/2025\/wp-json\/wp\/v2\/sessions\/2606\/revisions"}],"predecessor-version":[{"id":2710,"href":"https:\/\/madrid.wordcamp.org\/2025\/wp-json\/wp\/v2\/sessions\/2606\/revisions\/2710"}],"speakers":[{"embeddable":true,"href":"https:\/\/madrid.wordcamp.org\/2025\/wp-json\/wp\/v2\/speakers\/2544"}],"author":[{"embeddable":true,"href":"https:\/\/madrid.wordcamp.org\/2025\/wp-json\/wporg\/v1\/users\/unintended8"}],"wp:attachment":[{"href":"https:\/\/madrid.wordcamp.org\/2025\/wp-json\/wp\/v2\/media?parent=2606"}],"wp:term":[{"taxonomy":"wcb_track","embeddable":true,"href":"https:\/\/madrid.wordcamp.org\/2025\/wp-json\/wp\/v2\/session_track?post=2606"},{"taxonomy":"wcb_session_category","embeddable":true,"href":"https:\/\/madrid.wordcamp.org\/2025\/wp-json\/wp\/v2\/session_category?post=2606"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}